{"id":4571,"count":2,"description":"","link":"https:\/\/dorogimedence.hu\/index.php\/tag\/zold-ovoda\/","name":"Z\u00f6ld \u00d3voda","slug":"zold-ovoda","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Z\u00f6ld \u00d3voda Arch\u00edvum - Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/tag\/zold-ovoda\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Z\u00f6ld \u00d3voda Arch\u00edvum - Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/tag\/zold-ovoda\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/tag\\\/zold-ovoda\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/tag\\\/zold-ovoda\\\/\",\"name\":\"Z\u00f6ld \u00d3voda Arch\u00edvum - Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/tag\\\/zold-ovoda\\\/#breadcrumb\"},\"inLanguage\":\"hu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/tag\\\/zold-ovoda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Z\u00f6ld \u00d3voda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Z\u00f6ld \u00d3voda Arch\u00edvum - Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/tag\/zold-ovoda\/","og_locale":"hu_HU","og_type":"article","og_title":"Z\u00f6ld \u00d3voda Arch\u00edvum - Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","og_url":"https:\/\/dorogimedence.hu\/index.php\/tag\/zold-ovoda\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/dorogimedence.hu\/index.php\/tag\/zold-ovoda\/","url":"https:\/\/dorogimedence.hu\/index.php\/tag\/zold-ovoda\/","name":"Z\u00f6ld \u00d3voda Arch\u00edvum - Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/tag\/zold-ovoda\/#breadcrumb"},"inLanguage":"hu"},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/tag\/zold-ovoda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"Z\u00f6ld \u00d3voda"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags\/4571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts?tags=4571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}