{"id":9602,"date":"2018-04-19T16:50:11","date_gmt":"2018-04-19T14:50:11","guid":{"rendered":"http:\/\/dorogimedence.hu\/?p=9602"},"modified":"2018-04-20T06:46:39","modified_gmt":"2018-04-20T04:46:39","slug":"baleset-a-tati-elagazasnal","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/baleset-a-tati-elagazasnal\/","title":{"rendered":"Baleset a t\u00e1ti el\u00e1gaz\u00e1sn\u00e1l"},"content":{"rendered":"<p><strong>Cs\u00fct\u00f6rt\u00f6k d\u00e9lut\u00e1n f\u00e9l \u00f6tkor egy kisteheraut\u00f3 \u00e9s egy szem\u00e9lyaut\u00f3 \u00fctk\u00f6z\u00f6tt \u00f6ssze a 117-es \u00fat \u00e9s az Esztergomi \u00fat keresztez\u0151d\u00e9s\u00e9n\u00e9l T\u00e1t t\u00e9rs\u00e9g\u00e9ben.<\/strong><\/p>\n<p>A balesethez a nyerges\u00fajfalui hivat\u00e1sos t\u0171zolt\u00f3kat riasztott\u00e1k, akik megkezdt\u00e9k a j\u00e1rm\u0171vek \u00e1ramtalan\u00edt\u00e1s\u00e1t. Az \u00e9rintett \u00fatszakaszon f\u00e9lp\u00e1ly\u00e1n halad a forgalom.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cs\u00fct\u00f6rt\u00f6k d\u00e9lut\u00e1n f\u00e9l \u00f6tkor egy kisteheraut\u00f3 \u00e9s egy szem\u00e9lyaut\u00f3 \u00fctk\u00f6z\u00f6tt \u00f6ssze a 117-es \u00fat \u00e9s az Esztergomi \u00fat keresztez\u0151d\u00e9s\u00e9n\u00e9l T\u00e1t t\u00e9rs\u00e9g\u00e9ben. A balesethez a nyerges\u00fajfalui hivat\u00e1sos t\u0171zolt\u00f3kat riasztott\u00e1k, akik megkezdt\u00e9k a j\u00e1rm\u0171vek \u00e1ramtalan\u00edt\u00e1s\u00e1t. Az \u00e9rintett \u00fatszakaszon f\u00e9lp\u00e1ly\u00e1n halad a forgalom.<\/p>\n","protected":false},"author":1,"featured_media":6264,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,39,110],"tags":[],"class_list":["post-9602","post","type-post","status-publish","format-standard","has-post-thumbnail","category-hirek","category-kek-hirek","category-tat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Baleset a t\u00e1ti el\u00e1gaz\u00e1sn\u00e1l<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/baleset-a-tati-elagazasnal\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Baleset a t\u00e1ti el\u00e1gaz\u00e1sn\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Cs\u00fct\u00f6rt\u00f6k d\u00e9lut\u00e1n f\u00e9l \u00f6tkor egy kisteheraut\u00f3 \u00e9s egy szem\u00e9lyaut\u00f3 \u00fctk\u00f6z\u00f6tt \u00f6ssze a 117-es \u00fat \u00e9s az Esztergomi \u00fat keresztez\u0151d\u00e9s\u00e9n\u00e9l T\u00e1t t\u00e9rs\u00e9g\u00e9ben. A balesethez a nyerges\u00fajfalui hivat\u00e1sos t\u0171zolt\u00f3kat riasztott\u00e1k, akik megkezdt\u00e9k a j\u00e1rm\u0171vek \u00e1ramtalan\u00edt\u00e1s\u00e1t. Az \u00e9rintett \u00fatszakaszon f\u00e9lp\u00e1ly\u00e1n halad a forgalom.\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/baleset-a-tati-elagazasnal\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-19T14:50:11+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-20T04:46:39+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/10\/autobaleset-01.jpg?fit=670%2C365&ssl=1\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/baleset-a-tati-elagazasnal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/baleset-a-tati-elagazasnal\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"Baleset a t\u00e1ti el\u00e1gaz\u00e1sn\u00e1l\",\"datePublished\":\"2018-04-19T14:50:11+00:00\",\"dateModified\":\"2018-04-20T04:46:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/baleset-a-tati-elagazasnal\\\/\"},\"wordCount\":79,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/baleset-a-tati-elagazasnal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/autobaleset-01.jpg\",\"articleSection\":[\"H\u00edrek\",\"K\u00e9k h\u00edrek\",\"T\u00e1t\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/baleset-a-tati-elagazasnal\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/baleset-a-tati-elagazasnal\\\/\",\"name\":\"Baleset a t\u00e1ti el\u00e1gaz\u00e1sn\u00e1l\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/baleset-a-tati-elagazasnal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/baleset-a-tati-elagazasnal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/autobaleset-01.jpg\",\"datePublished\":\"2018-04-19T14:50:11+00:00\",\"dateModified\":\"2018-04-20T04:46:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/baleset-a-tati-elagazasnal\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/baleset-a-tati-elagazasnal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/baleset-a-tati-elagazasnal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/autobaleset-01.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/autobaleset-01.jpg\",\"width\":670,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/baleset-a-tati-elagazasnal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Baleset a t\u00e1ti el\u00e1gaz\u00e1sn\u00e1l\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Baleset a t\u00e1ti el\u00e1gaz\u00e1sn\u00e1l","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/baleset-a-tati-elagazasnal\/","og_locale":"hu_HU","og_type":"article","og_title":"Baleset a t\u00e1ti el\u00e1gaz\u00e1sn\u00e1l","og_description":"Cs\u00fct\u00f6rt\u00f6k d\u00e9lut\u00e1n f\u00e9l \u00f6tkor egy kisteheraut\u00f3 \u00e9s egy szem\u00e9lyaut\u00f3 \u00fctk\u00f6z\u00f6tt \u00f6ssze a 117-es \u00fat \u00e9s az Esztergomi \u00fat keresztez\u0151d\u00e9s\u00e9n\u00e9l T\u00e1t t\u00e9rs\u00e9g\u00e9ben. A balesethez a nyerges\u00fajfalui hivat\u00e1sos t\u0171zolt\u00f3kat riasztott\u00e1k, akik megkezdt\u00e9k a j\u00e1rm\u0171vek \u00e1ramtalan\u00edt\u00e1s\u00e1t. Az \u00e9rintett \u00fatszakaszon f\u00e9lp\u00e1ly\u00e1n halad a forgalom.","og_url":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/baleset-a-tati-elagazasnal\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2018-04-19T14:50:11+00:00","article_modified_time":"2018-04-20T04:46:39+00:00","og_image":[{"width":670,"height":365,"url":"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/10\/autobaleset-01.jpg?fit=670%2C365&ssl=1","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/baleset-a-tati-elagazasnal\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/baleset-a-tati-elagazasnal\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"Baleset a t\u00e1ti el\u00e1gaz\u00e1sn\u00e1l","datePublished":"2018-04-19T14:50:11+00:00","dateModified":"2018-04-20T04:46:39+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/baleset-a-tati-elagazasnal\/"},"wordCount":79,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/baleset-a-tati-elagazasnal\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/10\/autobaleset-01.jpg","articleSection":["H\u00edrek","K\u00e9k h\u00edrek","T\u00e1t"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/baleset-a-tati-elagazasnal\/","url":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/baleset-a-tati-elagazasnal\/","name":"Baleset a t\u00e1ti el\u00e1gaz\u00e1sn\u00e1l","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/baleset-a-tati-elagazasnal\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/baleset-a-tati-elagazasnal\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/10\/autobaleset-01.jpg","datePublished":"2018-04-19T14:50:11+00:00","dateModified":"2018-04-20T04:46:39+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/baleset-a-tati-elagazasnal\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/baleset-a-tati-elagazasnal\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/baleset-a-tati-elagazasnal\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/10\/autobaleset-01.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/10\/autobaleset-01.jpg","width":670,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/baleset-a-tati-elagazasnal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"Baleset a t\u00e1ti el\u00e1gaz\u00e1sn\u00e1l"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/9602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=9602"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/9602\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/6264"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=9602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=9602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=9602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}