{"id":9587,"date":"2018-04-19T14:49:36","date_gmt":"2018-04-19T12:49:36","guid":{"rendered":"http:\/\/dorogimedence.hu\/?p=9587"},"modified":"2018-04-20T12:30:37","modified_gmt":"2018-04-20T10:30:37","slug":"motoros-baleset-dorogon","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/motoros-baleset-dorogon\/","title":{"rendered":"Motoros baleset Dorogon"},"content":{"rendered":"<p><strong>Egy szem\u00e9lyg\u00e9pkocsi \u00e9s egy motorker\u00e9kp\u00e1r \u00fctk\u00f6z\u00f6tt \u00f6ssze \u00e1prilis 19-\u00e9n, cs\u00fct\u00f6rt\u00f6k d\u00e9lel\u0151tt Dorogon az Esztergomi \u00faton a Lidl \u00e9s a Spar el\u0151tti keresztez\u0151d\u00e9sben.<\/strong><\/p>\n<p>A motoros az eset sor\u00e1n s\u00falyosan megs\u00e9r\u00fclt, akit a ment\u0151k a helysz\u00ednen ell\u00e1ttak \u00e9s elsz\u00e1ll\u00edtottak.<\/p>\n<p><span style=\"color: #ff0000;\"><em><strong>Friss\u00edt\u00e9s (police.hu):<\/strong> <\/em><\/span>Egy 74 \u00e9ves f\u00e9rfi k\u00f6zlekedett 2018. \u00e1prilis 19-\u00e9n 10 \u00f3ra 35 perckor egy Toyota t\u00edpus\u00fa szem\u00e9lyg\u00e9pkocsival Dorogon, az Esztergomi \u00faton. Halad\u00e1sa sor\u00e1n, a B\u00e1ny\u00e1sz k\u00f6r\u00f6ndh\u00f6z \u00e9rve balra kanyarodott, azonban nem biztos\u00edtott els\u0151bbs\u00e9get a szemb\u0151l \u00e9rkez\u0151, \u00e9s egyenesen tov\u00e1bbhaladni sz\u00e1nd\u00e9koz\u00f3 motorker\u00e9kp\u00e1r vezet\u0151je r\u00e9sz\u00e9re \u00e9s \u00f6ssze\u00fctk\u00f6ztek. A balesetben a motorker\u00e9kp\u00e1rt vezet\u0151 22 \u00e9ves f\u00e9rfi s\u00falyosan s\u00e9r\u00fclt.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-9590\" src=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/motorbaleset-dorog2.jpg\" alt=\"\" width=\"670\" height=\"308\" srcset=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/motorbaleset-dorog2.jpg 670w, https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/motorbaleset-dorog2-300x138.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-9594\" src=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/motorbaleset-dorog3.jpg\" alt=\"\" width=\"670\" height=\"365\" srcset=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/motorbaleset-dorog3.jpg 670w, https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/motorbaleset-dorog3-300x163.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/p>\n<p><em>Fot\u00f3k: k\u00e9t olvas\u00f3nk<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Egy szem\u00e9lyg\u00e9pkocsi \u00e9s egy motorker\u00e9kp\u00e1r \u00fctk\u00f6z\u00f6tt \u00f6ssze \u00e1prilis 19-\u00e9n, cs\u00fct\u00f6rt\u00f6k d\u00e9lel\u0151tt Dorogon az Esztergomi \u00faton a Lidl \u00e9s a Spar el\u0151tti keresztez\u0151d\u00e9sben. A motoros az eset sor\u00e1n s\u00falyosan megs\u00e9r\u00fclt, akit a ment\u0151k a helysz\u00ednen ell\u00e1ttak \u00e9s elsz\u00e1ll\u00edtottak. Friss\u00edt\u00e9s (police.hu): Egy 74 \u00e9ves f\u00e9rfi k\u00f6zlekedett 2018. \u00e1prilis 19-\u00e9n 10 \u00f3ra 35 perckor egy Toyota t\u00edpus\u00fa szem\u00e9lyg\u00e9pkocsival<\/p>\n","protected":false},"author":1,"featured_media":9592,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[2,3,39],"tags":[45,44,15,675,61],"class_list":["post-9587","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dorog","category-hirek","category-kek-hirek","tag-autobaleset","tag-baleset","tag-dorog","tag-motorbaleset","tag-rendorsegi-hirek"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Motoros baleset Dorogon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/motoros-baleset-dorogon\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Motoros baleset Dorogon\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Egy szem\u00e9lyg\u00e9pkocsi \u00e9s egy motorker\u00e9kp\u00e1r \u00fctk\u00f6z\u00f6tt \u00f6ssze \u00e1prilis 19-\u00e9n, cs\u00fct\u00f6rt\u00f6k d\u00e9lel\u0151tt Dorogon az Esztergomi \u00faton a Lidl \u00e9s a Spar el\u0151tti keresztez\u0151d\u00e9sben. A motoros az eset sor\u00e1n s\u00falyosan megs\u00e9r\u00fclt, akit a ment\u0151k a helysz\u00ednen ell\u00e1ttak \u00e9s elsz\u00e1ll\u00edtottak. Friss\u00edt\u00e9s (police.hu): Egy 74 \u00e9ves f\u00e9rfi k\u00f6zlekedett 2018. \u00e1prilis 19-\u00e9n 10 \u00f3ra 35 perckor egy Toyota t\u00edpus\u00fa szem\u00e9lyg\u00e9pkocsival\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/motoros-baleset-dorogon\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-19T12:49:36+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-20T10:30:37+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/motorbaleset-dorog1.jpg?fit=670%2C365&ssl=1\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 perc\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/motoros-baleset-dorogon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/motoros-baleset-dorogon\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"Motoros baleset Dorogon\",\"datePublished\":\"2018-04-19T12:49:36+00:00\",\"dateModified\":\"2018-04-20T10:30:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/motoros-baleset-dorogon\\\/\"},\"wordCount\":157,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/motoros-baleset-dorogon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/motorbaleset-dorog1.jpg\",\"keywords\":[\"aut\u00f3baleset\",\"baleset\",\"Dorog\",\"motorbaleset\",\"rend\u0151rs\u00e9gi h\u00edrek\"],\"articleSection\":[\"Dorog\",\"H\u00edrek\",\"K\u00e9k h\u00edrek\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/motoros-baleset-dorogon\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/motoros-baleset-dorogon\\\/\",\"name\":\"Motoros baleset Dorogon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/motoros-baleset-dorogon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/motoros-baleset-dorogon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/motorbaleset-dorog1.jpg\",\"datePublished\":\"2018-04-19T12:49:36+00:00\",\"dateModified\":\"2018-04-20T10:30:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/motoros-baleset-dorogon\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/motoros-baleset-dorogon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/motoros-baleset-dorogon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/motorbaleset-dorog1.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/motorbaleset-dorog1.jpg\",\"width\":670,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/19\\\/motoros-baleset-dorogon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Motoros baleset Dorogon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Motoros baleset Dorogon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/motoros-baleset-dorogon\/","og_locale":"hu_HU","og_type":"article","og_title":"Motoros baleset Dorogon","og_description":"Egy szem\u00e9lyg\u00e9pkocsi \u00e9s egy motorker\u00e9kp\u00e1r \u00fctk\u00f6z\u00f6tt \u00f6ssze \u00e1prilis 19-\u00e9n, cs\u00fct\u00f6rt\u00f6k d\u00e9lel\u0151tt Dorogon az Esztergomi \u00faton a Lidl \u00e9s a Spar el\u0151tti keresztez\u0151d\u00e9sben. A motoros az eset sor\u00e1n s\u00falyosan megs\u00e9r\u00fclt, akit a ment\u0151k a helysz\u00ednen ell\u00e1ttak \u00e9s elsz\u00e1ll\u00edtottak. Friss\u00edt\u00e9s (police.hu): Egy 74 \u00e9ves f\u00e9rfi k\u00f6zlekedett 2018. \u00e1prilis 19-\u00e9n 10 \u00f3ra 35 perckor egy Toyota t\u00edpus\u00fa szem\u00e9lyg\u00e9pkocsival","og_url":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/motoros-baleset-dorogon\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2018-04-19T12:49:36+00:00","article_modified_time":"2018-04-20T10:30:37+00:00","og_image":[{"width":670,"height":365,"url":"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/motorbaleset-dorog1.jpg?fit=670%2C365&ssl=1","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu","Becs\u00fclt olvas\u00e1si id\u0151":"1 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/motoros-baleset-dorogon\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/motoros-baleset-dorogon\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"Motoros baleset Dorogon","datePublished":"2018-04-19T12:49:36+00:00","dateModified":"2018-04-20T10:30:37+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/motoros-baleset-dorogon\/"},"wordCount":157,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/motoros-baleset-dorogon\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/motorbaleset-dorog1.jpg","keywords":["aut\u00f3baleset","baleset","Dorog","motorbaleset","rend\u0151rs\u00e9gi h\u00edrek"],"articleSection":["Dorog","H\u00edrek","K\u00e9k h\u00edrek"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/motoros-baleset-dorogon\/","url":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/motoros-baleset-dorogon\/","name":"Motoros baleset Dorogon","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/motoros-baleset-dorogon\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/motoros-baleset-dorogon\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/motorbaleset-dorog1.jpg","datePublished":"2018-04-19T12:49:36+00:00","dateModified":"2018-04-20T10:30:37+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/motoros-baleset-dorogon\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/motoros-baleset-dorogon\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/motoros-baleset-dorogon\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/motorbaleset-dorog1.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/motorbaleset-dorog1.jpg","width":670,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/19\/motoros-baleset-dorogon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"Motoros baleset Dorogon"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/9587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=9587"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/9587\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/9592"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=9587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=9587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=9587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}