{"id":9362,"date":"2018-04-07T09:28:32","date_gmt":"2018-04-07T07:28:32","guid":{"rendered":"http:\/\/dorogimedence.hu\/?p=9362"},"modified":"2018-04-07T09:28:32","modified_gmt":"2018-04-07T07:28:32","slug":"bubik-istvanra-emlekeznek-esztergomban","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/07\/bubik-istvanra-emlekeznek-esztergomban\/","title":{"rendered":"Bubik Istv\u00e1nra eml\u00e9keznek Esztergomban"},"content":{"rendered":"<p><strong>\u00c1prilis 21-\u00e9n a 2004-ben, tragikus aut\u00f3balesetben elhunyt Bubik Istv\u00e1nra eml\u00e9keznek Esztergomban. A J\u00e1szai Mari-d\u00edjas magyar sz\u00ednm\u0171v\u00e9sz, \u00e9rdemes m\u0171v\u00e9sz a Temesv\u00e1ri Pelb\u00e1rt Ferences Gimn\u00e1ziumban v\u00e9gezte tanulm\u00e1nyait.<\/strong><\/p>\n<p>Gy\u00fclekez\u0151 14 \u00f3ra 30 perckor, a Franka el\u0151tt, majd k\u00f6z\u00f6s s\u00e9ta a Bubik Istv\u00e1n utc\u00e1ba, ahol eml\u00e9kt\u00e1bl\u00e1t helyeznek el a n\u00e9vad\u00f3r\u00f3l.\u00a0 Az avat\u00e1son k\u00f6sz\u00f6nt\u0151t mond Romanek Etelka, Esztergom v\u00e1ros polg\u00e1rmestere \u00e9s Kaj \u00c1d\u00e1m, a Babits Mih\u00e1ly Kamarat\u00e1rsulat vezet\u0151je.<\/p>\n<p>Az \u00f6regdi\u00e1kok nev\u00e9ben eml\u00e9kezik, \u00e9s az eml\u00e9kt\u00e1bl\u00e1t meg\u00e1ldja P. Tok\u00e1r J\u00e1nos OFM, a Temesv\u00e1ri Pelb\u00e1rt Ferences Gimn\u00e1zium volt igazgat\u00f3ja.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c1prilis 21-\u00e9n a 2004-ben, tragikus aut\u00f3balesetben elhunyt Bubik Istv\u00e1nra eml\u00e9keznek Esztergomban. A J\u00e1szai Mari-d\u00edjas magyar sz\u00ednm\u0171v\u00e9sz, \u00e9rdemes m\u0171v\u00e9sz a Temesv\u00e1ri Pelb\u00e1rt Ferences Gimn\u00e1ziumban v\u00e9gezte tanulm\u00e1nyait. Gy\u00fclekez\u0151 14 \u00f3ra 30 perckor, a Franka el\u0151tt, majd k\u00f6z\u00f6s s\u00e9ta a Bubik Istv\u00e1n utc\u00e1ba, ahol eml\u00e9kt\u00e1bl\u00e1t helyeznek el a n\u00e9vad\u00f3r\u00f3l.\u00a0 Az avat\u00e1son k\u00f6sz\u00f6nt\u0151t mond Romanek Etelka, Esztergom v\u00e1ros polg\u00e1rmestere<\/p>\n","protected":false},"author":1,"featured_media":9363,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[38,3],"tags":[],"class_list":["post-9362","post","type-post","status-publish","format-standard","has-post-thumbnail","category-esztergom","category-hirek"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bubik Istv\u00e1nra eml\u00e9keznek Esztergomban<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/07\/bubik-istvanra-emlekeznek-esztergomban\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Bubik Istv\u00e1nra eml\u00e9keznek Esztergomban\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"\u00c1prilis 21-\u00e9n a 2004-ben, tragikus aut\u00f3balesetben elhunyt Bubik Istv\u00e1nra eml\u00e9keznek Esztergomban. A J\u00e1szai Mari-d\u00edjas magyar sz\u00ednm\u0171v\u00e9sz, \u00e9rdemes m\u0171v\u00e9sz a Temesv\u00e1ri Pelb\u00e1rt Ferences Gimn\u00e1ziumban v\u00e9gezte tanulm\u00e1nyait. Gy\u00fclekez\u0151 14 \u00f3ra 30 perckor, a Franka el\u0151tt, majd k\u00f6z\u00f6s s\u00e9ta a Bubik Istv\u00e1n utc\u00e1ba, ahol eml\u00e9kt\u00e1bl\u00e1t helyeznek el a n\u00e9vad\u00f3r\u00f3l.\u00a0 Az avat\u00e1son k\u00f6sz\u00f6nt\u0151t mond Romanek Etelka, Esztergom v\u00e1ros polg\u00e1rmestere\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/07\/bubik-istvanra-emlekeznek-esztergomban\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-07T07:28:32+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/bubik.jpg?fit=670%2C365&ssl=1\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 perc\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/07\\\/bubik-istvanra-emlekeznek-esztergomban\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/07\\\/bubik-istvanra-emlekeznek-esztergomban\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"Bubik Istv\u00e1nra eml\u00e9keznek Esztergomban\",\"datePublished\":\"2018-04-07T07:28:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/07\\\/bubik-istvanra-emlekeznek-esztergomban\\\/\"},\"wordCount\":138,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/07\\\/bubik-istvanra-emlekeznek-esztergomban\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/bubik.jpg\",\"articleSection\":[\"Esztergom\",\"H\u00edrek\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/07\\\/bubik-istvanra-emlekeznek-esztergomban\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/07\\\/bubik-istvanra-emlekeznek-esztergomban\\\/\",\"name\":\"Bubik Istv\u00e1nra eml\u00e9keznek Esztergomban\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/07\\\/bubik-istvanra-emlekeznek-esztergomban\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/07\\\/bubik-istvanra-emlekeznek-esztergomban\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/bubik.jpg\",\"datePublished\":\"2018-04-07T07:28:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/07\\\/bubik-istvanra-emlekeznek-esztergomban\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/07\\\/bubik-istvanra-emlekeznek-esztergomban\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/07\\\/bubik-istvanra-emlekeznek-esztergomban\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/bubik.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/bubik.jpg\",\"width\":670,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/04\\\/07\\\/bubik-istvanra-emlekeznek-esztergomban\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bubik Istv\u00e1nra eml\u00e9keznek Esztergomban\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bubik Istv\u00e1nra eml\u00e9keznek Esztergomban","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/07\/bubik-istvanra-emlekeznek-esztergomban\/","og_locale":"hu_HU","og_type":"article","og_title":"Bubik Istv\u00e1nra eml\u00e9keznek Esztergomban","og_description":"\u00c1prilis 21-\u00e9n a 2004-ben, tragikus aut\u00f3balesetben elhunyt Bubik Istv\u00e1nra eml\u00e9keznek Esztergomban. A J\u00e1szai Mari-d\u00edjas magyar sz\u00ednm\u0171v\u00e9sz, \u00e9rdemes m\u0171v\u00e9sz a Temesv\u00e1ri Pelb\u00e1rt Ferences Gimn\u00e1ziumban v\u00e9gezte tanulm\u00e1nyait. Gy\u00fclekez\u0151 14 \u00f3ra 30 perckor, a Franka el\u0151tt, majd k\u00f6z\u00f6s s\u00e9ta a Bubik Istv\u00e1n utc\u00e1ba, ahol eml\u00e9kt\u00e1bl\u00e1t helyeznek el a n\u00e9vad\u00f3r\u00f3l.\u00a0 Az avat\u00e1son k\u00f6sz\u00f6nt\u0151t mond Romanek Etelka, Esztergom v\u00e1ros polg\u00e1rmestere","og_url":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/07\/bubik-istvanra-emlekeznek-esztergomban\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2018-04-07T07:28:32+00:00","og_image":[{"width":670,"height":365,"url":"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/bubik.jpg?fit=670%2C365&ssl=1","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu","Becs\u00fclt olvas\u00e1si id\u0151":"1 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/07\/bubik-istvanra-emlekeznek-esztergomban\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/07\/bubik-istvanra-emlekeznek-esztergomban\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"Bubik Istv\u00e1nra eml\u00e9keznek Esztergomban","datePublished":"2018-04-07T07:28:32+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/07\/bubik-istvanra-emlekeznek-esztergomban\/"},"wordCount":138,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/07\/bubik-istvanra-emlekeznek-esztergomban\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/bubik.jpg","articleSection":["Esztergom","H\u00edrek"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/07\/bubik-istvanra-emlekeznek-esztergomban\/","url":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/07\/bubik-istvanra-emlekeznek-esztergomban\/","name":"Bubik Istv\u00e1nra eml\u00e9keznek Esztergomban","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/07\/bubik-istvanra-emlekeznek-esztergomban\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/07\/bubik-istvanra-emlekeznek-esztergomban\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/bubik.jpg","datePublished":"2018-04-07T07:28:32+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/07\/bubik-istvanra-emlekeznek-esztergomban\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2018\/04\/07\/bubik-istvanra-emlekeznek-esztergomban\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/07\/bubik-istvanra-emlekeznek-esztergomban\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/bubik.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/04\/bubik.jpg","width":670,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/04\/07\/bubik-istvanra-emlekeznek-esztergomban\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"Bubik Istv\u00e1nra eml\u00e9keznek Esztergomban"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/9362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=9362"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/9362\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/9363"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=9362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=9362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=9362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}