{"id":7485,"date":"2017-12-28T09:23:42","date_gmt":"2017-12-28T08:23:42","guid":{"rendered":"http:\/\/dorogimedence.hu\/?p=7485"},"modified":"2017-12-28T09:23:42","modified_gmt":"2017-12-28T08:23:42","slug":"bajnai-arokban-landolt-a-citroen","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/28\/bajnai-arokban-landolt-a-citroen\/","title":{"rendered":"Bajnai \u00e1rokban landolt a Citro\u00ebn"},"content":{"rendered":"<p><strong>Egy 69 \u00e9ves bicskei lakos december 27-\u00e9n 12 \u00f3ra 45 perckor egy Citro\u00ebn t\u00edpus\u00fa szem\u00e9lyg\u00e9pkocsival k\u00f6zlekedett az 1105-\u00f6s sz\u00e1m\u00fa \u00faton Bajna fel\u0151l Gyermely ir\u00e1ny\u00e1ba.<\/strong><\/p>\n<p>A 10-es kilom\u00e9terszelv\u00e9nyben j\u00e1rm\u0171ve sebess\u00e9g\u00e9t nem az \u00fatviszonyoknak megfelel\u0151en v\u00e1lasztotta meg, megcs\u00faszott \u00e9s az \u00fat jobb sz\u00e9le melletti \u00e1rokpartnak \u00fctk\u00f6z\u00f6tt. A baleset sor\u00e1n egy szem\u00e9ly k\u00f6nnyen s\u00e9r\u00fclt.<\/p>\n<p><em>Fot\u00f3, forr\u00e1s: police.hu<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Egy 69 \u00e9ves bicskei lakos december 27-\u00e9n 12 \u00f3ra 45 perckor egy Citro\u00ebn t\u00edpus\u00fa szem\u00e9lyg\u00e9pkocsival k\u00f6zlekedett az 1105-\u00f6s sz\u00e1m\u00fa \u00faton Bajna fel\u0151l Gyermely ir\u00e1ny\u00e1ba. A 10-es kilom\u00e9terszelv\u00e9nyben j\u00e1rm\u0171ve sebess\u00e9g\u00e9t nem az \u00fatviszonyoknak megfelel\u0151en v\u00e1lasztotta meg, megcs\u00faszott \u00e9s az \u00fat jobb sz\u00e9le melletti \u00e1rokpartnak \u00fctk\u00f6z\u00f6tt. A baleset sor\u00e1n egy szem\u00e9ly k\u00f6nnyen s\u00e9r\u00fclt. Fot\u00f3, forr\u00e1s: police.hu<\/p>\n","protected":false},"author":1,"featured_media":7486,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,39],"tags":[45,249,44,679,61],"class_list":["post-7485","post","type-post","status-publish","format-standard","has-post-thumbnail","category-hirek","category-kek-hirek","tag-autobaleset","tag-bajna","tag-baleset","tag-gyermely","tag-rendorsegi-hirek"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bajnai \u00e1rokban landolt a Citro\u00ebn<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/28\/bajnai-arokban-landolt-a-citroen\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Bajnai \u00e1rokban landolt a Citro\u00ebn\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Egy 69 \u00e9ves bicskei lakos december 27-\u00e9n 12 \u00f3ra 45 perckor egy Citro\u00ebn t\u00edpus\u00fa szem\u00e9lyg\u00e9pkocsival k\u00f6zlekedett az 1105-\u00f6s sz\u00e1m\u00fa \u00faton Bajna fel\u0151l Gyermely ir\u00e1ny\u00e1ba. A 10-es kilom\u00e9terszelv\u00e9nyben j\u00e1rm\u0171ve sebess\u00e9g\u00e9t nem az \u00fatviszonyoknak megfelel\u0151en v\u00e1lasztotta meg, megcs\u00faszott \u00e9s az \u00fat jobb sz\u00e9le melletti \u00e1rokpartnak \u00fctk\u00f6z\u00f6tt. A baleset sor\u00e1n egy szem\u00e9ly k\u00f6nnyen s\u00e9r\u00fclt. Fot\u00f3, forr\u00e1s: police.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/28\/bajnai-arokban-landolt-a-citroen\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-28T08:23:42+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/12\/bajna-baleset-08.jpg?fit=670%2C365&ssl=1\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/28\\\/bajnai-arokban-landolt-a-citroen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/28\\\/bajnai-arokban-landolt-a-citroen\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"Bajnai \u00e1rokban landolt a Citro\u00ebn\",\"datePublished\":\"2017-12-28T08:23:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/28\\\/bajnai-arokban-landolt-a-citroen\\\/\"},\"wordCount\":87,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/28\\\/bajnai-arokban-landolt-a-citroen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/bajna-baleset-08.jpg\",\"keywords\":[\"aut\u00f3baleset\",\"Bajna\",\"baleset\",\"Gyermely\",\"rend\u0151rs\u00e9gi h\u00edrek\"],\"articleSection\":[\"H\u00edrek\",\"K\u00e9k h\u00edrek\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/28\\\/bajnai-arokban-landolt-a-citroen\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/28\\\/bajnai-arokban-landolt-a-citroen\\\/\",\"name\":\"Bajnai \u00e1rokban landolt a Citro\u00ebn\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/28\\\/bajnai-arokban-landolt-a-citroen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/28\\\/bajnai-arokban-landolt-a-citroen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/bajna-baleset-08.jpg\",\"datePublished\":\"2017-12-28T08:23:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/28\\\/bajnai-arokban-landolt-a-citroen\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/28\\\/bajnai-arokban-landolt-a-citroen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/28\\\/bajnai-arokban-landolt-a-citroen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/bajna-baleset-08.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/bajna-baleset-08.jpg\",\"width\":670,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/28\\\/bajnai-arokban-landolt-a-citroen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bajnai \u00e1rokban landolt a Citro\u00ebn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bajnai \u00e1rokban landolt a Citro\u00ebn","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/28\/bajnai-arokban-landolt-a-citroen\/","og_locale":"hu_HU","og_type":"article","og_title":"Bajnai \u00e1rokban landolt a Citro\u00ebn","og_description":"Egy 69 \u00e9ves bicskei lakos december 27-\u00e9n 12 \u00f3ra 45 perckor egy Citro\u00ebn t\u00edpus\u00fa szem\u00e9lyg\u00e9pkocsival k\u00f6zlekedett az 1105-\u00f6s sz\u00e1m\u00fa \u00faton Bajna fel\u0151l Gyermely ir\u00e1ny\u00e1ba. A 10-es kilom\u00e9terszelv\u00e9nyben j\u00e1rm\u0171ve sebess\u00e9g\u00e9t nem az \u00fatviszonyoknak megfelel\u0151en v\u00e1lasztotta meg, megcs\u00faszott \u00e9s az \u00fat jobb sz\u00e9le melletti \u00e1rokpartnak \u00fctk\u00f6z\u00f6tt. A baleset sor\u00e1n egy szem\u00e9ly k\u00f6nnyen s\u00e9r\u00fclt. Fot\u00f3, forr\u00e1s: police.hu","og_url":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/28\/bajnai-arokban-landolt-a-citroen\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2017-12-28T08:23:42+00:00","og_image":[{"width":670,"height":365,"url":"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/12\/bajna-baleset-08.jpg?fit=670%2C365&ssl=1","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/28\/bajnai-arokban-landolt-a-citroen\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/28\/bajnai-arokban-landolt-a-citroen\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"Bajnai \u00e1rokban landolt a Citro\u00ebn","datePublished":"2017-12-28T08:23:42+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/28\/bajnai-arokban-landolt-a-citroen\/"},"wordCount":87,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/28\/bajnai-arokban-landolt-a-citroen\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/12\/bajna-baleset-08.jpg","keywords":["aut\u00f3baleset","Bajna","baleset","Gyermely","rend\u0151rs\u00e9gi h\u00edrek"],"articleSection":["H\u00edrek","K\u00e9k h\u00edrek"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/28\/bajnai-arokban-landolt-a-citroen\/","url":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/28\/bajnai-arokban-landolt-a-citroen\/","name":"Bajnai \u00e1rokban landolt a Citro\u00ebn","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/28\/bajnai-arokban-landolt-a-citroen\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/28\/bajnai-arokban-landolt-a-citroen\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/12\/bajna-baleset-08.jpg","datePublished":"2017-12-28T08:23:42+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/28\/bajnai-arokban-landolt-a-citroen\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2017\/12\/28\/bajnai-arokban-landolt-a-citroen\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/28\/bajnai-arokban-landolt-a-citroen\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/12\/bajna-baleset-08.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/12\/bajna-baleset-08.jpg","width":670,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/28\/bajnai-arokban-landolt-a-citroen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"Bajnai \u00e1rokban landolt a Citro\u00ebn"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/7485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=7485"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/7485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/7486"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=7485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=7485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=7485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}