{"id":7225,"date":"2017-12-09T09:16:35","date_gmt":"2017-12-09T08:16:35","guid":{"rendered":"http:\/\/dorogimedence.hu\/?p=7225"},"modified":"2017-12-09T09:16:35","modified_gmt":"2017-12-09T08:16:35","slug":"nemzetisegi-egyuttesek-talalkoztak","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/09\/nemzetisegi-egyuttesek-talalkoztak\/","title":{"rendered":"Nemzetis\u00e9gi egy\u00fcttesek tal\u00e1lkoztak"},"content":{"rendered":"<p><strong>A megyei \u00f6nkorm\u00e1nyzat \u00e1ltal szervezett \u201e\u00c9rt\u00e9keink a k\u00f6z\u00e9ppontban\u201d c\u00edm\u0171 rendezv\u00e9ny keret\u00e9ben 22. alkalommal tartott\u00e1k meg a Kom\u00e1rom-Esztergom Megyei Nemzetis\u00e9gi Egy\u00fcttesek Tal\u00e1lkoz\u00f3j\u00e1t p\u00e9nteken Oroszl\u00e1nyban, ahol t\u00e9rs\u00e9g\u00fcnkb\u0151l Keszt\u00f6lc \u00e9s S\u00e1ris\u00e1p is k\u00e9pviselte mag\u00e1t.<\/strong><\/p>\n<p>Az oroszl\u00e1nyi M\u0171vel\u0151d\u00e9si H\u00e1zban rendezett eg\u00e9sz napos, nagyszab\u00e1s\u00fa rendezv\u00e9ny d\u00e9lut\u00e1ni r\u00e9sz\u00e9ben ker\u00fclt sor az egy\u00fcttesek fell\u00e9p\u00e9s\u00e9re. A csoportok tal\u00e1lkoz\u00f3j\u00e1t Laz\u00f3k Zolt\u00e1n, Oroszl\u00e1ny polg\u00e1rmester\u00e9nek \u00e9s Szab\u00f3 Istv\u00e1n Lajosn\u00e9, a Kom\u00e1rom-Esztergom Megyei \u00e9s az Oroszl\u00e1nyi Szlov\u00e1k \u00d6nkorm\u00e1nyzat eln\u00f6k\u00e9nek k\u00f6sz\u00f6nt\u0151je nyitotta meg. Popovics Gy\u00f6rgy, a megyei k\u00f6zgy\u0171l\u00e9s eln\u00f6ke besz\u00e9d\u00e9ben elmondta, a Megyei \u00c9rt\u00e9kt\u00e1rban jelenleg t\u00f6bb mint 100 megyei \u00e9rt\u00e9k tal\u00e1lhat\u00f3, melyek k\u00f6z\u00f6tt szerepelnek nemzetis\u00e9gi \u00e9rt\u00e9kek is, de kor\u00e1nt sem olyan sz\u00e1mban, mint amit a nemzetis\u00e9gek sz\u00e1ma \u00e9s jelent\u0151s\u00e9ge indokolna. \u201eA mai rendezv\u00e9ny\u00fcnkkel, a nemzetis\u00e9gek \u00fcnnep\u00e9vel arra szeretn\u00e9nk \u00f6szt\u00f6n\u00f6zni a nemzetis\u00e9gek k\u00e9pvisel\u0151it, hogy gy\u0171jts\u00e9k identit\u00e1sukat meghat\u00e1roz\u00f3 \u00e9rt\u00e9keiket, hiszen ezek szerves alkot\u00f3i elemei magyars\u00e1gunknak\u201d \u2013 tette hozz\u00e1.<\/p>\n<p>A tal\u00e1lkoz\u00f3n ez\u00fattal 16 csoport l\u00e9pett sz\u00ednpadra sz\u00ednvonalas m\u0171sor\u00e1val, k\u00f6zt\u00fck szlov\u00e1k, n\u00e9met \u00e9s roma nemzetis\u00e9gi csoportok is. A helyi csoportok mellett Tatab\u00e1ny\u00e1r\u00f3l, Tarj\u00e1nb\u00f3l, Keszt\u00f6lcr\u0151l, Tardosr\u00f3l, Szomorr\u00f3l, S\u00e1ris\u00e1pr\u00f3l \u00e9s V\u00e9rtessoml\u00f3r\u00f3l is \u00e9rkeztek fell\u00e9p\u0151k. A rendezv\u00e9ny Veres Zolt\u00e1n megyei jegyz\u0151 z\u00e1rszav\u00e1val \u00e9rt v\u00e9get.<\/p>\n<p><em>Fot\u00f3, forr\u00e1s: KEM\u00d6H Sajt\u00f3<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A megyei \u00f6nkorm\u00e1nyzat \u00e1ltal szervezett \u201e\u00c9rt\u00e9keink a k\u00f6z\u00e9ppontban\u201d c\u00edm\u0171 rendezv\u00e9ny keret\u00e9ben 22. alkalommal tartott\u00e1k meg a Kom\u00e1rom-Esztergom Megyei Nemzetis\u00e9gi Egy\u00fcttesek Tal\u00e1lkoz\u00f3j\u00e1t p\u00e9nteken Oroszl\u00e1nyban, ahol t\u00e9rs\u00e9g\u00fcnkb\u0151l Keszt\u00f6lc \u00e9s S\u00e1ris\u00e1p is k\u00e9pviselte mag\u00e1t. Az oroszl\u00e1nyi M\u0171vel\u0151d\u00e9si H\u00e1zban rendezett eg\u00e9sz napos, nagyszab\u00e1s\u00fa rendezv\u00e9ny d\u00e9lut\u00e1ni r\u00e9sz\u00e9ben ker\u00fclt sor az egy\u00fcttesek fell\u00e9p\u00e9s\u00e9re. A csoportok tal\u00e1lkoz\u00f3j\u00e1t Laz\u00f3k Zolt\u00e1n, Oroszl\u00e1ny polg\u00e1rmester\u00e9nek \u00e9s<\/p>\n","protected":false},"author":1,"featured_media":7226,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,8,56],"tags":[173,129,1949,423],"class_list":["post-7225","post","type-post","status-publish","format-standard","has-post-thumbnail","category-hirek","category-kesztolc","category-komarom-esztergom","tag-eloadas","tag-kesztolc","tag-nemzetisegek","tag-sarisap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nemzetis\u00e9gi egy\u00fcttesek tal\u00e1lkoztak<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/09\/nemzetisegi-egyuttesek-talalkoztak\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Nemzetis\u00e9gi egy\u00fcttesek tal\u00e1lkoztak\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"A megyei \u00f6nkorm\u00e1nyzat \u00e1ltal szervezett \u201e\u00c9rt\u00e9keink a k\u00f6z\u00e9ppontban\u201d c\u00edm\u0171 rendezv\u00e9ny keret\u00e9ben 22. alkalommal tartott\u00e1k meg a Kom\u00e1rom-Esztergom Megyei Nemzetis\u00e9gi Egy\u00fcttesek Tal\u00e1lkoz\u00f3j\u00e1t p\u00e9nteken Oroszl\u00e1nyban, ahol t\u00e9rs\u00e9g\u00fcnkb\u0151l Keszt\u00f6lc \u00e9s S\u00e1ris\u00e1p is k\u00e9pviselte mag\u00e1t. Az oroszl\u00e1nyi M\u0171vel\u0151d\u00e9si H\u00e1zban rendezett eg\u00e9sz napos, nagyszab\u00e1s\u00fa rendezv\u00e9ny d\u00e9lut\u00e1ni r\u00e9sz\u00e9ben ker\u00fclt sor az egy\u00fcttesek fell\u00e9p\u00e9s\u00e9re. A csoportok tal\u00e1lkoz\u00f3j\u00e1t Laz\u00f3k Zolt\u00e1n, Oroszl\u00e1ny polg\u00e1rmester\u00e9nek \u00e9s\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/09\/nemzetisegi-egyuttesek-talalkoztak\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-09T08:16:35+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/12\/nemzetisegek-talalkozoja.jpg?fit=670%2C365&ssl=1\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 perc\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/09\\\/nemzetisegi-egyuttesek-talalkoztak\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/09\\\/nemzetisegi-egyuttesek-talalkoztak\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"Nemzetis\u00e9gi egy\u00fcttesek tal\u00e1lkoztak\",\"datePublished\":\"2017-12-09T08:16:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/09\\\/nemzetisegi-egyuttesek-talalkoztak\\\/\"},\"wordCount\":316,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/09\\\/nemzetisegi-egyuttesek-talalkoztak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/nemzetisegek-talalkozoja.jpg\",\"keywords\":[\"el\u0151ad\u00e1s\",\"Keszt\u00f6lc\",\"nemzetis\u00e9gek\",\"S\u00e1ris\u00e1p\"],\"articleSection\":[\"H\u00edrek\",\"Keszt\u00f6lc\",\"Kom\u00e1rom-Esztergom\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/09\\\/nemzetisegi-egyuttesek-talalkoztak\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/09\\\/nemzetisegi-egyuttesek-talalkoztak\\\/\",\"name\":\"Nemzetis\u00e9gi egy\u00fcttesek tal\u00e1lkoztak\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/09\\\/nemzetisegi-egyuttesek-talalkoztak\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/09\\\/nemzetisegi-egyuttesek-talalkoztak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/nemzetisegek-talalkozoja.jpg\",\"datePublished\":\"2017-12-09T08:16:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/09\\\/nemzetisegi-egyuttesek-talalkoztak\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/09\\\/nemzetisegi-egyuttesek-talalkoztak\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/09\\\/nemzetisegi-egyuttesek-talalkoztak\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/nemzetisegek-talalkozoja.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/nemzetisegek-talalkozoja.jpg\",\"width\":670,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/12\\\/09\\\/nemzetisegi-egyuttesek-talalkoztak\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nemzetis\u00e9gi egy\u00fcttesek tal\u00e1lkoztak\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nemzetis\u00e9gi egy\u00fcttesek tal\u00e1lkoztak","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/09\/nemzetisegi-egyuttesek-talalkoztak\/","og_locale":"hu_HU","og_type":"article","og_title":"Nemzetis\u00e9gi egy\u00fcttesek tal\u00e1lkoztak","og_description":"A megyei \u00f6nkorm\u00e1nyzat \u00e1ltal szervezett \u201e\u00c9rt\u00e9keink a k\u00f6z\u00e9ppontban\u201d c\u00edm\u0171 rendezv\u00e9ny keret\u00e9ben 22. alkalommal tartott\u00e1k meg a Kom\u00e1rom-Esztergom Megyei Nemzetis\u00e9gi Egy\u00fcttesek Tal\u00e1lkoz\u00f3j\u00e1t p\u00e9nteken Oroszl\u00e1nyban, ahol t\u00e9rs\u00e9g\u00fcnkb\u0151l Keszt\u00f6lc \u00e9s S\u00e1ris\u00e1p is k\u00e9pviselte mag\u00e1t. Az oroszl\u00e1nyi M\u0171vel\u0151d\u00e9si H\u00e1zban rendezett eg\u00e9sz napos, nagyszab\u00e1s\u00fa rendezv\u00e9ny d\u00e9lut\u00e1ni r\u00e9sz\u00e9ben ker\u00fclt sor az egy\u00fcttesek fell\u00e9p\u00e9s\u00e9re. A csoportok tal\u00e1lkoz\u00f3j\u00e1t Laz\u00f3k Zolt\u00e1n, Oroszl\u00e1ny polg\u00e1rmester\u00e9nek \u00e9s","og_url":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/09\/nemzetisegi-egyuttesek-talalkoztak\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2017-12-09T08:16:35+00:00","og_image":[{"width":670,"height":365,"url":"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/12\/nemzetisegek-talalkozoja.jpg?fit=670%2C365&ssl=1","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu","Becs\u00fclt olvas\u00e1si id\u0151":"2 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/09\/nemzetisegi-egyuttesek-talalkoztak\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/09\/nemzetisegi-egyuttesek-talalkoztak\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"Nemzetis\u00e9gi egy\u00fcttesek tal\u00e1lkoztak","datePublished":"2017-12-09T08:16:35+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/09\/nemzetisegi-egyuttesek-talalkoztak\/"},"wordCount":316,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/09\/nemzetisegi-egyuttesek-talalkoztak\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/12\/nemzetisegek-talalkozoja.jpg","keywords":["el\u0151ad\u00e1s","Keszt\u00f6lc","nemzetis\u00e9gek","S\u00e1ris\u00e1p"],"articleSection":["H\u00edrek","Keszt\u00f6lc","Kom\u00e1rom-Esztergom"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/09\/nemzetisegi-egyuttesek-talalkoztak\/","url":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/09\/nemzetisegi-egyuttesek-talalkoztak\/","name":"Nemzetis\u00e9gi egy\u00fcttesek tal\u00e1lkoztak","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/09\/nemzetisegi-egyuttesek-talalkoztak\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/09\/nemzetisegi-egyuttesek-talalkoztak\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/12\/nemzetisegek-talalkozoja.jpg","datePublished":"2017-12-09T08:16:35+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/09\/nemzetisegi-egyuttesek-talalkoztak\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2017\/12\/09\/nemzetisegi-egyuttesek-talalkoztak\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/09\/nemzetisegi-egyuttesek-talalkoztak\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/12\/nemzetisegek-talalkozoja.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/12\/nemzetisegek-talalkozoja.jpg","width":670,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/12\/09\/nemzetisegi-egyuttesek-talalkoztak\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"Nemzetis\u00e9gi egy\u00fcttesek tal\u00e1lkoztak"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/7225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=7225"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/7225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/7226"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=7225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=7225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=7225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}