{"id":6598,"date":"2017-11-02T19:45:24","date_gmt":"2017-11-02T18:45:24","guid":{"rendered":"http:\/\/dorogimedence.hu\/?p=6598"},"modified":"2017-11-02T19:45:24","modified_gmt":"2017-11-02T18:45:24","slug":"egyre-tobben-parkolnak-szabalytalanul-dorogon","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2017\/11\/02\/egyre-tobben-parkolnak-szabalytalanul-dorogon\/","title":{"rendered":"Egyre t\u00f6bben parkolnak szab\u00e1lytalanul Dorogon"},"content":{"rendered":"<p><strong>Egyre t\u00f6bben v\u00e1lasztj\u00e1k g\u00e9pj\u00e1rm\u0171v\u00fckkel a j\u00e1rd\u00e1n val\u00f3 szab\u00e1lytalan parkol\u00e1st Dorog \u00e9s a t\u00e9rs\u00e9gben. Napi szinten ker\u00fclnek fel fot\u00f3k a Facebook k\u00f6z\u00f6ss\u00e9gi oldalra a felh\u00e1borodott gyalogosokt\u00f3l &#8211; legt\u00f6bb esetben jogosan.<\/strong><\/p>\n<p>Fontos figyelembe venni, hogy nem csak gyalogosan k\u00f6zlekednek a j\u00e1rd\u00e1n, hiszen az anyuk\u00e1k a babakocsit is ott tolj\u00e1k. Ha egy aut\u00f3s teljes sz\u00e9less\u00e9g\u00e9ben elfoglalja a j\u00e1rd\u00e1t, akkor a babakocsit az \u00fattestre kell tolni, ami balesetvesz\u00e9lyes. Tov\u00e1bb\u00e1 a mozg\u00e1ss\u00e9r\u00fclteknek is komoly gondot okoz az aut\u00f3k kiker\u00fcl\u00e9se az \u00fattesten.<\/p>\n<p>Szeretn\u00e9nk felh\u00edvni, azon aut\u00f3sok figyelm\u00e9t akik nem, vagy csak r\u00e9szben ismerik a <strong>KRESZ 40. paragrafus\u00e1nak 8. pontj\u00e1t<\/strong>:<\/p>\n<p>\u201eA j\u00e1rd\u00e1n \u2013 r\u00e9szben vagy teljes terjedelemben \u2013 csak akkor szabad meg\u00e1llni, ha<br \/>\na) azt jelz\u0151t\u00e1bla vagy \u00fatburkolati jel megengedi,<br \/>\nb) a j\u00e1rm\u0171 a j\u00e1rda sz\u00e9less\u00e9g\u00e9nek legfeljebb a fel\u00e9t foglalja el,<br \/>\nc) a j\u00e1rd\u00e1n a gyalogosok k\u00f6zleked\u00e9s\u00e9re legal\u00e1bb 1,5 m\u00e9ter szabadon marad, \u00e9s<br \/>\nd) a j\u00e1rm\u0171 tengelyterhel\u00e9se az 1000 kg-ot nem haladja meg.\u201d<\/p>\n<p><b>A j\u00e1rd\u00e1n (ak\u00e1r r\u00e9szben) meg\u00e1llni csak a n\u00e9gy felt\u00e9tel egyidej\u0171 teljes\u00fcl\u00e9sekor szab\u00e1lyos.<\/b><\/p>\n<p>A j\u00e1rda fogalm\u00e1t a KRESZ I. sz\u00e1m\u00fa f\u00fcggel\u00e9ke egy\u00e9rtelm\u0171en hat\u00e1rozza meg. J\u00e1rda: az \u00fatnak a gyalogosok k\u00f6zleked\u00e9s\u00e9re szolg\u00e1l\u00f3 \u2013 az \u00fattestt\u0151l szintk\u00fcl\u00f6nbs\u00e9ggel, kiemelt szeg\u00e9llyel, vagy m\u00e1s l\u00e1that\u00f3 m\u00f3don elhat\u00e1rolt \u2013 r\u00e9sze; a gyalog\u00fat azonban nem j\u00e1rda.<\/p>\n<p><em>Fot\u00f3: Szondi Ildik\u00f3 (10-es \u00fat Facebook csoport)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Egyre t\u00f6bben v\u00e1lasztj\u00e1k g\u00e9pj\u00e1rm\u0171v\u00fckkel a j\u00e1rd\u00e1n val\u00f3 szab\u00e1lytalan parkol\u00e1st Dorog \u00e9s a t\u00e9rs\u00e9gben. Napi szinten ker\u00fclnek fel fot\u00f3k a Facebook k\u00f6z\u00f6ss\u00e9gi oldalra a felh\u00e1borodott gyalogosokt\u00f3l &#8211; legt\u00f6bb esetben jogosan. Fontos figyelembe venni, hogy nem csak gyalogosan k\u00f6zlekednek a j\u00e1rd\u00e1n, hiszen az anyuk\u00e1k a babakocsit is ott tolj\u00e1k. Ha egy aut\u00f3s teljes sz\u00e9less\u00e9g\u00e9ben elfoglalja a j\u00e1rd\u00e1t,<\/p>\n","protected":false},"author":1,"featured_media":6599,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[2,3],"tags":[15,512,1793],"class_list":{"0":"post-6598","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dorog","8":"category-hirek","9":"tag-dorog","10":"tag-parkolas","11":"tag-szabalytalan-parkolas"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Egyre t\u00f6bben parkolnak szab\u00e1lytalanul Dorogon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2017\/11\/02\/egyre-tobben-parkolnak-szabalytalanul-dorogon\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Egyre t\u00f6bben parkolnak szab\u00e1lytalanul Dorogon\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Egyre t\u00f6bben v\u00e1lasztj\u00e1k g\u00e9pj\u00e1rm\u0171v\u00fckkel a j\u00e1rd\u00e1n val\u00f3 szab\u00e1lytalan parkol\u00e1st Dorog \u00e9s a t\u00e9rs\u00e9gben. Napi szinten ker\u00fclnek fel fot\u00f3k a Facebook k\u00f6z\u00f6ss\u00e9gi oldalra a felh\u00e1borodott gyalogosokt\u00f3l &#8211; legt\u00f6bb esetben jogosan. Fontos figyelembe venni, hogy nem csak gyalogosan k\u00f6zlekednek a j\u00e1rd\u00e1n, hiszen az anyuk\u00e1k a babakocsit is ott tolj\u00e1k. Ha egy aut\u00f3s teljes sz\u00e9less\u00e9g\u00e9ben elfoglalja a j\u00e1rd\u00e1t,\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2017\/11\/02\/egyre-tobben-parkolnak-szabalytalanul-dorogon\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-02T18:45:24+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/11\/parkolas-dorog.jpg?fit=670%2C365&ssl=1\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 perc\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/11\\\/02\\\/egyre-tobben-parkolnak-szabalytalanul-dorogon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/11\\\/02\\\/egyre-tobben-parkolnak-szabalytalanul-dorogon\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"Egyre t\u00f6bben parkolnak szab\u00e1lytalanul Dorogon\",\"datePublished\":\"2017-11-02T18:45:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/11\\\/02\\\/egyre-tobben-parkolnak-szabalytalanul-dorogon\\\/\"},\"wordCount\":303,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/11\\\/02\\\/egyre-tobben-parkolnak-szabalytalanul-dorogon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/parkolas-dorog.jpg\",\"keywords\":[\"Dorog\",\"parkol\u00e1s\",\"szab\u00e1lytalan parkol\u00e1s\"],\"articleSection\":[\"Dorog\",\"H\u00edrek\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/11\\\/02\\\/egyre-tobben-parkolnak-szabalytalanul-dorogon\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/11\\\/02\\\/egyre-tobben-parkolnak-szabalytalanul-dorogon\\\/\",\"name\":\"Egyre t\u00f6bben parkolnak szab\u00e1lytalanul Dorogon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/11\\\/02\\\/egyre-tobben-parkolnak-szabalytalanul-dorogon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/11\\\/02\\\/egyre-tobben-parkolnak-szabalytalanul-dorogon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/parkolas-dorog.jpg\",\"datePublished\":\"2017-11-02T18:45:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/11\\\/02\\\/egyre-tobben-parkolnak-szabalytalanul-dorogon\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/11\\\/02\\\/egyre-tobben-parkolnak-szabalytalanul-dorogon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/11\\\/02\\\/egyre-tobben-parkolnak-szabalytalanul-dorogon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/parkolas-dorog.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/parkolas-dorog.jpg\",\"width\":670,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/11\\\/02\\\/egyre-tobben-parkolnak-szabalytalanul-dorogon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Egyre t\u00f6bben parkolnak szab\u00e1lytalanul Dorogon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Egyre t\u00f6bben parkolnak szab\u00e1lytalanul Dorogon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2017\/11\/02\/egyre-tobben-parkolnak-szabalytalanul-dorogon\/","og_locale":"hu_HU","og_type":"article","og_title":"Egyre t\u00f6bben parkolnak szab\u00e1lytalanul Dorogon","og_description":"Egyre t\u00f6bben v\u00e1lasztj\u00e1k g\u00e9pj\u00e1rm\u0171v\u00fckkel a j\u00e1rd\u00e1n val\u00f3 szab\u00e1lytalan parkol\u00e1st Dorog \u00e9s a t\u00e9rs\u00e9gben. Napi szinten ker\u00fclnek fel fot\u00f3k a Facebook k\u00f6z\u00f6ss\u00e9gi oldalra a felh\u00e1borodott gyalogosokt\u00f3l &#8211; legt\u00f6bb esetben jogosan. Fontos figyelembe venni, hogy nem csak gyalogosan k\u00f6zlekednek a j\u00e1rd\u00e1n, hiszen az anyuk\u00e1k a babakocsit is ott tolj\u00e1k. Ha egy aut\u00f3s teljes sz\u00e9less\u00e9g\u00e9ben elfoglalja a j\u00e1rd\u00e1t,","og_url":"https:\/\/dorogimedence.hu\/index.php\/2017\/11\/02\/egyre-tobben-parkolnak-szabalytalanul-dorogon\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2017-11-02T18:45:24+00:00","og_image":[{"width":670,"height":365,"url":"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/11\/parkolas-dorog.jpg?fit=670%2C365&ssl=1","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu","Becs\u00fclt olvas\u00e1si id\u0151":"1 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/11\/02\/egyre-tobben-parkolnak-szabalytalanul-dorogon\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/11\/02\/egyre-tobben-parkolnak-szabalytalanul-dorogon\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"Egyre t\u00f6bben parkolnak szab\u00e1lytalanul Dorogon","datePublished":"2017-11-02T18:45:24+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/11\/02\/egyre-tobben-parkolnak-szabalytalanul-dorogon\/"},"wordCount":303,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/11\/02\/egyre-tobben-parkolnak-szabalytalanul-dorogon\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/11\/parkolas-dorog.jpg","keywords":["Dorog","parkol\u00e1s","szab\u00e1lytalan parkol\u00e1s"],"articleSection":["Dorog","H\u00edrek"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/11\/02\/egyre-tobben-parkolnak-szabalytalanul-dorogon\/","url":"https:\/\/dorogimedence.hu\/index.php\/2017\/11\/02\/egyre-tobben-parkolnak-szabalytalanul-dorogon\/","name":"Egyre t\u00f6bben parkolnak szab\u00e1lytalanul Dorogon","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/11\/02\/egyre-tobben-parkolnak-szabalytalanul-dorogon\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/11\/02\/egyre-tobben-parkolnak-szabalytalanul-dorogon\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/11\/parkolas-dorog.jpg","datePublished":"2017-11-02T18:45:24+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/11\/02\/egyre-tobben-parkolnak-szabalytalanul-dorogon\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2017\/11\/02\/egyre-tobben-parkolnak-szabalytalanul-dorogon\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/11\/02\/egyre-tobben-parkolnak-szabalytalanul-dorogon\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/11\/parkolas-dorog.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/11\/parkolas-dorog.jpg","width":670,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/11\/02\/egyre-tobben-parkolnak-szabalytalanul-dorogon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"Egyre t\u00f6bben parkolnak szab\u00e1lytalanul Dorogon"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/6598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=6598"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/6598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/6599"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=6598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=6598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=6598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}