{"id":56775,"date":"2023-10-02T11:20:43","date_gmt":"2023-10-02T09:20:43","guid":{"rendered":"https:\/\/dorogimedence.hu\/?p=56775"},"modified":"2023-10-02T11:20:43","modified_gmt":"2023-10-02T09:20:43","slug":"kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2023\/10\/02\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/","title":{"rendered":"Kihirdett\u00e9k a 6. Blue Danube Filmfesztiv\u00e1l d\u00edjazottjait"},"content":{"rendered":"<p><strong>Id\u00e9n el\u0151sz\u00f6r a Duna Sell\u0151 kateg\u00f3ri\u00e1ban, a Duna-r\u00e9gi\u00f3ban \u00e9l\u0151 n\u0151i alkot\u00f3k legjobb r\u00f6vidfilmjei is versenyeztek a 4 v\u00e1rosban &#8211; B\u00e9cs, Budapest, Pozsony, Esztergom (Kaleidoszk\u00f3p H\u00e1z) &#8211; megrendezett fesztiv\u00e1lon.<\/strong> <strong>K\u00e9t magyar film is a d\u00edjazottak k\u00f6z\u00f6tt van, \u00edgy Beleznai M\u00e1rk Kakukkfi\u00f3ka valamint Gyimesi Anna Affrik\u00e1ta c\u00edm\u0171 filmje is<\/strong> <em>&#8211; \u00edrja a <\/em><a href=\"https:\/\/felvidek.ma\/2023\/10\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline; color: #0000ff;\"><em>Felvid\u00e9k.ma<\/em><\/span><\/a><\/p>\n<p><strong>A kateg\u00f3ria gy\u0151ztese Gyimesi Anna Szarajev\u00f3ban is bemutatott Affrik\u00e1ta c\u00edm\u0171 filmje lett.<\/strong> A zs\u0171ri \u00e9rt\u00e9kel\u00e9se szerint a rendez\u0151n\u0151nek a csod\u00e1val hat\u00e1ros m\u00f3don siker\u00fcl sokf\u00e9le t\u00e9m\u00e1t \u2013 anyas\u00e1g, n\u0151i l\u00e9t, tin\u00e9dzserkori szorong\u00e1s, fogyat\u00e9kkal \u00e9l\u0151k egy\u00fctt\u00e9l\u00e9se\u2026 \u2013 \u00f6sszefonni, ami minden m\u00e1s r\u00f6vidfilmben t\u00fal sok lett volna. K\u00fcl\u00f6nd\u00edjat kapott a Berlinale-n is bemutatott ukr\u00e1n It\u201ds A Date c\u00edm\u0171 film Nadia Parfant\u00f3l.<\/p>\n<p><strong>A narrat\u00edv r\u00f6vidfilmek kateg\u00f3ri\u00e1j\u00e1ban magyar siker sz\u00fcletett, Beleznai M\u00e1rk alkot\u00e1sa, a Kakukkfi\u00f3ka lett a legjobb film. <\/strong>A zs\u0171ri indokl\u00e1sa szerint az egy fiatal feln\u0151tt \u00e9s egy serd\u00fcl\u0151 f\u00e9ltestv\u00e9r tal\u00e1lkoz\u00e1s\u00e1nak t\u00f6rt\u00e9nete m\u00e9ly, \u00f6sszetett t\u00f6rt\u00e9net. Kapcsolatuk megfogalmaz\u00e1sa a film tet\u0151pontj\u00e1n egy spont\u00e1n t\u00e1nc kiemelked\u0151 filmes pillanata: a szabads\u00e1g, a r\u00f6vid id\u0151re egym\u00e1sra \u00e9s \u00f6nmagunkra tal\u00e1l\u00e1s ingatag csod\u00e1ja. A film az egyik leg\u00e9get\u0151bb t\u00e1rsadalmi kr\u00edzis\u00fcnk m\u00e9lyen humanista megk\u00f6zel\u00edt\u00e9s\u0171, letisztult formavil\u00e1g\u00fa, megind\u00edt\u00f3an sz\u00e9p \u00e1br\u00e1zol\u00e1sa.<\/p>\n<p>Az anim\u00e1ci\u00f3s kateg\u00f3ri\u00e1ban a francia Carla Melo Gampert nyert La Perra, m\u00edg a dokumentumfilmek k\u00f6z\u00f6tt a sv\u00e1jci Marie Chemin kapta a f\u0151d\u00edjat a \u201eThe Ghost from Mariupol\u201d l\u00edrai-meditat\u00edv filmj\u00e9vel. A finn Saara Ekstr\u00f6m Amnion c\u00edm\u0171 filmje a k\u00eds\u00e9rleti filmek k\u00f6z\u00f6tt, m\u00edg az 5 percn\u00e9l r\u00f6videbb filmeknek fenntartott Super Short kateg\u00f3ria f\u0151d\u00edjasa egy alb\u00e1n film, a Two Suns in the Sunset lett Gentian Gjikopullit\u00f3l.<\/p>\n<p>A nemzetk\u00f6zi zs\u0171ri tagjai id\u00e9n Noemie Nakai jap\u00e1n-francia sz\u00edn\u00e9szn\u0151 \u00e9s filmrendez\u0151n\u0151,&nbsp; Camila Kater brazil anim\u00e1ci\u00f3s filmrendez\u0151n\u0151, Richard Tuohy ausztr\u00e1l filmrendez\u0151, fesztiv\u00e1lszervez\u0151 \u00e9s dr. Gelencs\u00e9r G\u00e1bor, az ELTE habilit\u00e1lt egyetemi docense, Bal\u00e1zs B\u00e9la-d\u00edjas filmeszt\u00e9ta voltak.<\/p>\n<p>A nemzetk\u00f6zi zs\u0171ri mellett egy egyetemi zs\u0171ri is d\u00f6nt\u00f6tt az \u00e1ltaluk legjobbnak tartott filmekr\u0151l. A zs\u0171ri tagjai filmes szakokra j\u00e1r\u00f3 egyetemist\u00e1k, n\u00e9v szerint Sorosi Eszter, Szokol Judit, T\u00f3th Lili, Fekete R\u00f3bert, G\u00e1l Andr\u00e1s \u00e9s Horv\u00e1th Mih\u00e1ly.<\/p>\n<p>Az egyetemi zs\u0171ri d\u00edjazottjai a Duna Sell\u0151 kateg\u00f3ri\u00e1j\u00e1ban a szlov\u00e1k Alica Bedn\u00e1rikov\u00e1t\u00f3l a Liquid Bread, a Short kateg\u00f3ri\u00e1ban a lengyel Jan Bujnowskit\u00f3l a The Devil, &nbsp;a Super Short kateg\u00f3ri\u00e1ban az amerikai Brian Ratigent\u0151l A Body Apperaed at the Lake Today, az osztr\u00e1k Total Refusal anim\u00e1ci\u00f3ja a Hardly Working, a holland Douwe Dijkstra dokumentumfilmje, a Neighbour Abdi \u00e9s az amerikai Brice Bowman k\u00eds\u00e9rleti filmje, a Museum Closed lett.<\/p>\n<p>A&nbsp; fesztiv\u00e1l k\u00eds\u00e9r\u0151 programj\u00e1ban t\u00f6bb besz\u00e9lget\u00e9s is szerepelt alkot\u00f3kkal, forgat\u00f3k\u00f6nyv\u00edr\u00f3kkal, filmeszt\u00e9t\u00e1kkal, filmt\u00f6rt\u00e9n\u00e9szekkel, valamint a filmek t\u00e9m\u00e1ihoz kapcsol\u00f3d\u00f3 szak\u00e9rt\u0151kkel.<\/p>\n<p>Tov\u00e1bbi inform\u00e1ci\u00f3k a fesztiv\u00e1l <a href=\"https:\/\/www.bluedanubefilmfestival.hu\/winners\" target=\"_blank\" rel=\"noopener\"><strong><span style=\"text-decoration: underline; color: #0000ff;\">hivatalos honlapj\u00e1n<\/span><\/strong><\/a>, valamint a <a href=\"https:\/\/www.facebook.com\/bluedanubefilmfestival\" target=\"_blank\" rel=\"noopener\"><strong><span style=\"text-decoration: underline; color: #0000ff;\">k\u00f6z\u00f6ss\u00e9gi oldal\u00e1n<\/span><\/strong><\/a> tal\u00e1lhat\u00f3ak.<\/p>\n<p><em>Forr\u00e1s: felvidek.ma<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Id\u00e9n el\u0151sz\u00f6r a Duna Sell\u0151 kateg\u00f3ri\u00e1ban, a Duna-r\u00e9gi\u00f3ban \u00e9l\u0151 n\u0151i alkot\u00f3k legjobb r\u00f6vidfilmjei is versenyeztek a 4 v\u00e1rosban &#8211; B\u00e9cs, Budapest, Pozsony, Esztergom (Kaleidoszk\u00f3p H\u00e1z) &#8211; megrendezett fesztiv\u00e1lon. K\u00e9t magyar film is a d\u00edjazottak k\u00f6z\u00f6tt van, \u00edgy Beleznai M\u00e1rk Kakukkfi\u00f3ka valamint Gyimesi Anna Affrik\u00e1ta c\u00edm\u0171 filmje is &#8211; \u00edrja a Felvid\u00e9k.ma A kateg\u00f3ria gy\u0151ztese Gyimesi<\/p>\n","protected":false},"author":1,"featured_media":56776,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[38,3],"tags":[7492,42,7491],"class_list":["post-56775","post","type-post","status-publish","format-standard","has-post-thumbnail","category-esztergom","category-hirek","tag-blue-danube","tag-esztergom","tag-filmfesztival"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kihirdett\u00e9k a 6. Blue Danube Filmfesztiv\u00e1l d\u00edjazottjait<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2023\/10\/02\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Kihirdett\u00e9k a 6. Blue Danube Filmfesztiv\u00e1l d\u00edjazottjait\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Id\u00e9n el\u0151sz\u00f6r a Duna Sell\u0151 kateg\u00f3ri\u00e1ban, a Duna-r\u00e9gi\u00f3ban \u00e9l\u0151 n\u0151i alkot\u00f3k legjobb r\u00f6vidfilmjei is versenyeztek a 4 v\u00e1rosban &#8211; B\u00e9cs, Budapest, Pozsony, Esztergom (Kaleidoszk\u00f3p H\u00e1z) &#8211; megrendezett fesztiv\u00e1lon. K\u00e9t magyar film is a d\u00edjazottak k\u00f6z\u00f6tt van, \u00edgy Beleznai M\u00e1rk Kakukkfi\u00f3ka valamint Gyimesi Anna Affrik\u00e1ta c\u00edm\u0171 filmje is &#8211; \u00edrja a Felvid\u00e9k.ma A kateg\u00f3ria gy\u0151ztese Gyimesi\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2023\/10\/02\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-02T09:20:43+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2023\/10\/blue-danube.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"970\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 perc\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/10\\\/02\\\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/10\\\/02\\\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"Kihirdett\u00e9k a 6. Blue Danube Filmfesztiv\u00e1l d\u00edjazottjait\",\"datePublished\":\"2023-10-02T09:20:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/10\\\/02\\\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\\\/\"},\"wordCount\":647,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/10\\\/02\\\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/blue-danube.jpg\",\"keywords\":[\"Blue Danube\",\"esztergom\",\"filmfesztiv\u00e1l\"],\"articleSection\":[\"Esztergom\",\"H\u00edrek\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/10\\\/02\\\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/10\\\/02\\\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\\\/\",\"name\":\"Kihirdett\u00e9k a 6. Blue Danube Filmfesztiv\u00e1l d\u00edjazottjait\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/10\\\/02\\\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/10\\\/02\\\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/blue-danube.jpg\",\"datePublished\":\"2023-10-02T09:20:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/10\\\/02\\\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/10\\\/02\\\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/10\\\/02\\\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/blue-danube.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/blue-danube.jpg\",\"width\":1920,\"height\":970},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/10\\\/02\\\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kihirdett\u00e9k a 6. Blue Danube Filmfesztiv\u00e1l d\u00edjazottjait\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kihirdett\u00e9k a 6. Blue Danube Filmfesztiv\u00e1l d\u00edjazottjait","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2023\/10\/02\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/","og_locale":"hu_HU","og_type":"article","og_title":"Kihirdett\u00e9k a 6. Blue Danube Filmfesztiv\u00e1l d\u00edjazottjait","og_description":"Id\u00e9n el\u0151sz\u00f6r a Duna Sell\u0151 kateg\u00f3ri\u00e1ban, a Duna-r\u00e9gi\u00f3ban \u00e9l\u0151 n\u0151i alkot\u00f3k legjobb r\u00f6vidfilmjei is versenyeztek a 4 v\u00e1rosban &#8211; B\u00e9cs, Budapest, Pozsony, Esztergom (Kaleidoszk\u00f3p H\u00e1z) &#8211; megrendezett fesztiv\u00e1lon. K\u00e9t magyar film is a d\u00edjazottak k\u00f6z\u00f6tt van, \u00edgy Beleznai M\u00e1rk Kakukkfi\u00f3ka valamint Gyimesi Anna Affrik\u00e1ta c\u00edm\u0171 filmje is &#8211; \u00edrja a Felvid\u00e9k.ma A kateg\u00f3ria gy\u0151ztese Gyimesi","og_url":"https:\/\/dorogimedence.hu\/index.php\/2023\/10\/02\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2023-10-02T09:20:43+00:00","og_image":[{"width":1920,"height":970,"url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2023\/10\/blue-danube.jpg","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu","Becs\u00fclt olvas\u00e1si id\u0151":"3 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/10\/02\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/10\/02\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"Kihirdett\u00e9k a 6. Blue Danube Filmfesztiv\u00e1l d\u00edjazottjait","datePublished":"2023-10-02T09:20:43+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/10\/02\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/"},"wordCount":647,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/10\/02\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2023\/10\/blue-danube.jpg","keywords":["Blue Danube","esztergom","filmfesztiv\u00e1l"],"articleSection":["Esztergom","H\u00edrek"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/10\/02\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/","url":"https:\/\/dorogimedence.hu\/index.php\/2023\/10\/02\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/","name":"Kihirdett\u00e9k a 6. Blue Danube Filmfesztiv\u00e1l d\u00edjazottjait","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/10\/02\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/10\/02\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2023\/10\/blue-danube.jpg","datePublished":"2023-10-02T09:20:43+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/10\/02\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2023\/10\/02\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/10\/02\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2023\/10\/blue-danube.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2023\/10\/blue-danube.jpg","width":1920,"height":970},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/10\/02\/kihirdettek-a-6-blue-danube-filmfesztival-dijazottjait\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"Kihirdett\u00e9k a 6. Blue Danube Filmfesztiv\u00e1l d\u00edjazottjait"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/56775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=56775"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/56775\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/56776"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=56775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=56775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=56775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}