{"id":50513,"date":"2023-02-21T10:28:32","date_gmt":"2023-02-21T09:28:32","guid":{"rendered":"https:\/\/dorogimedence.hu\/?p=50513"},"modified":"2023-02-21T10:28:50","modified_gmt":"2023-02-21T09:28:50","slug":"felpalyas-utlezaras-esztergomban-a-vaskapui-uton","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2023\/02\/21\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\/","title":{"rendered":"F\u00e9lp\u00e1ly\u00e1s \u00fatlez\u00e1r\u00e1s Esztergomban a Vaskapui \u00faton"},"content":{"rendered":"<p><strong>2023. febru\u00e1r 4-\u00e9n Esztergomban a tart\u00f3s \u00e9s heves es\u0151z\u00e9st k\u00f6vet\u0151en jelentkez\u0151 \u00e1rhull\u00e1m jelent\u0151sen megrong\u00e1lta a Vaskapui utat k\u00eds\u00e9r\u0151 Szent Gy\u00f6rgy \u00e1rok mederburkolat\u00e1t a K\u0151r\u00f6sy L\u00e1szl\u00f3 utca \u00e9s a Visegr\u00e1di \u00fat k\u00f6z\u00f6tti szakaszon<\/strong> <em>&#8211; k\u00f6z\u00f6lte Esztergom \u00f6nkorm\u00e1nyzata a hivatalos honlapj\u00e1n.<\/em><\/p>\n<p>A lez\u00fadul\u00f3 csapad\u00e9k al\u00e1mosta r\u00e9zs\u0171 k\u00f6r\u00f6mvonal\u00e1t. Az \u00fatr\u00f3l az \u00e1rokba foly\u00f3 v\u00edz a r\u00e9zs\u0171s mederpartfal m\u00f6g\u00e9 sziv\u00e1rgott, \u00e9s mintegy 15 m\u00e9ter hossz\u00fa szakaszon annak suvad\u00e1s\u00e1t okozta. Ezzel egyidej\u0171leg az \u00fat padka 10 m\u00e9teres szakasz\u00e1n reped\u00e9s keletkezett.<\/p>\n<p>A partfal oml\u00e1s vesz\u00e9lyezteti a k\u00f6zutat, a v\u00edzlevezet\u0151 \u00e1rkot \u00e9s a k\u00f6z\u00fati padk\u00e1ban elhelyezked\u0151 k\u00f6zm\u0171veket. Tekintettel arra, hogy a helysz\u00edn jelen form\u00e1j\u00e1ban balesetvesz\u00e9lyes, ez\u00e9rt a Magyar K\u00f6z\u00fat Nonprofit Zrt., mint az \u00fatszakasz kezel\u0151je int\u00e9zkedett a vesz\u00e9lyeztetett ter\u00fclet g\u00e9pj\u00e1rm\u0171forgalom el\u0151l t\u00f6rt\u00e9n\u0151 elz\u00e1r\u00e1sa ir\u00e1nt.<\/p>\n<p>Esztergom Megyei Jog\u00fa V\u00e1ros \u00d6nkorm\u00e1nyzata ezzel egyidej\u0171leg szak\u00e9rt\u0151k bevon\u00e1s\u00e1val megkezdte a k\u00e1rosodott \u00e1rokszakasz helyre\u00e1ll\u00edt\u00e1s\u00e1ra vonatkoz\u00f3 terv elk\u00e9sz\u00edt\u00e9s\u00e9t, \u00e9s a kivitelez\u00e9si munk\u00e1latok el\u0151k\u00e9sz\u00edt\u00e9s\u00e9t.<\/p>\n<p>K\u00e9rj\u00fck az arra j\u00e1r\u00f3kat, hogy az \u00e9rintett \u00fatszakaszon a megv\u00e1ltozott forgalmi rendnek megfelel\u0151en, fokozott \u00f3vatoss\u00e1ggal \u00e9s k\u00f6r\u00fcltekint\u0151en k\u00f6zlekedjenek!<\/p>\n<p><em>Forr\u00e1s: esztergom.hu<br \/>\nBor\u00edt\u00f3k\u00e9p: Google<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>2023. febru\u00e1r 4-\u00e9n Esztergomban a tart\u00f3s \u00e9s heves es\u0151z\u00e9st k\u00f6vet\u0151en jelentkez\u0151 \u00e1rhull\u00e1m jelent\u0151sen megrong\u00e1lta a Vaskapui utat k\u00eds\u00e9r\u0151 Szent Gy\u00f6rgy \u00e1rok mederburkolat\u00e1t a K\u0151r\u00f6sy L\u00e1szl\u00f3 utca \u00e9s a Visegr\u00e1di \u00fat k\u00f6z\u00f6tti szakaszon &#8211; k\u00f6z\u00f6lte Esztergom \u00f6nkorm\u00e1nyzata a hivatalos honlapj\u00e1n. A lez\u00fadul\u00f3 csapad\u00e9k al\u00e1mosta r\u00e9zs\u0171 k\u00f6r\u00f6mvonal\u00e1t. Az \u00fatr\u00f3l az \u00e1rokba foly\u00f3 v\u00edz a r\u00e9zs\u0171s mederpartfal m\u00f6g\u00e9<\/p>\n","protected":false},"author":1,"featured_media":50514,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[38,3],"tags":[42,6996,818,3183],"class_list":{"0":"post-50513","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-esztergom","8":"category-hirek","9":"tag-esztergom","10":"tag-felpalyas-utlezaras","11":"tag-utlezaras","12":"tag-vaskapui-ut"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>F\u00e9lp\u00e1ly\u00e1s \u00fatlez\u00e1r\u00e1s Esztergomban a Vaskapui \u00faton<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2023\/02\/21\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"F\u00e9lp\u00e1ly\u00e1s \u00fatlez\u00e1r\u00e1s Esztergomban a Vaskapui \u00faton\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"2023. febru\u00e1r 4-\u00e9n Esztergomban a tart\u00f3s \u00e9s heves es\u0151z\u00e9st k\u00f6vet\u0151en jelentkez\u0151 \u00e1rhull\u00e1m jelent\u0151sen megrong\u00e1lta a Vaskapui utat k\u00eds\u00e9r\u0151 Szent Gy\u00f6rgy \u00e1rok mederburkolat\u00e1t a K\u0151r\u00f6sy L\u00e1szl\u00f3 utca \u00e9s a Visegr\u00e1di \u00fat k\u00f6z\u00f6tti szakaszon &#8211; k\u00f6z\u00f6lte Esztergom \u00f6nkorm\u00e1nyzata a hivatalos honlapj\u00e1n. A lez\u00fadul\u00f3 csapad\u00e9k al\u00e1mosta r\u00e9zs\u0171 k\u00f6r\u00f6mvonal\u00e1t. Az \u00fatr\u00f3l az \u00e1rokba foly\u00f3 v\u00edz a r\u00e9zs\u0171s mederpartfal m\u00f6g\u00e9\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2023\/02\/21\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-21T09:28:32+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-21T09:28:50+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2023\/02\/vaskapui-ut.jpg\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1369\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"767\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 perc\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/02\\\/21\\\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/02\\\/21\\\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"F\u00e9lp\u00e1ly\u00e1s \u00fatlez\u00e1r\u00e1s Esztergomban a Vaskapui \u00faton\",\"datePublished\":\"2023-02-21T09:28:32+00:00\",\"dateModified\":\"2023-02-21T09:28:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/02\\\/21\\\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\\\/\"},\"wordCount\":281,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/02\\\/21\\\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/vaskapui-ut.jpg\",\"keywords\":[\"esztergom\",\"f\u00e9lp\u00e1ly\u00e1s \u00fatlez\u00e1r\u00e1s\",\"\u00fatlez\u00e1r\u00e1s\",\"Vaskapui \u00fat\"],\"articleSection\":[\"Esztergom\",\"H\u00edrek\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/02\\\/21\\\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/02\\\/21\\\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\\\/\",\"name\":\"F\u00e9lp\u00e1ly\u00e1s \u00fatlez\u00e1r\u00e1s Esztergomban a Vaskapui \u00faton\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/02\\\/21\\\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/02\\\/21\\\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/vaskapui-ut.jpg\",\"datePublished\":\"2023-02-21T09:28:32+00:00\",\"dateModified\":\"2023-02-21T09:28:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/02\\\/21\\\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/02\\\/21\\\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/02\\\/21\\\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/vaskapui-ut.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/vaskapui-ut.jpg\",\"width\":1369,\"height\":767},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2023\\\/02\\\/21\\\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F\u00e9lp\u00e1ly\u00e1s \u00fatlez\u00e1r\u00e1s Esztergomban a Vaskapui \u00faton\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"F\u00e9lp\u00e1ly\u00e1s \u00fatlez\u00e1r\u00e1s Esztergomban a Vaskapui \u00faton","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2023\/02\/21\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\/","og_locale":"hu_HU","og_type":"article","og_title":"F\u00e9lp\u00e1ly\u00e1s \u00fatlez\u00e1r\u00e1s Esztergomban a Vaskapui \u00faton","og_description":"2023. febru\u00e1r 4-\u00e9n Esztergomban a tart\u00f3s \u00e9s heves es\u0151z\u00e9st k\u00f6vet\u0151en jelentkez\u0151 \u00e1rhull\u00e1m jelent\u0151sen megrong\u00e1lta a Vaskapui utat k\u00eds\u00e9r\u0151 Szent Gy\u00f6rgy \u00e1rok mederburkolat\u00e1t a K\u0151r\u00f6sy L\u00e1szl\u00f3 utca \u00e9s a Visegr\u00e1di \u00fat k\u00f6z\u00f6tti szakaszon &#8211; k\u00f6z\u00f6lte Esztergom \u00f6nkorm\u00e1nyzata a hivatalos honlapj\u00e1n. A lez\u00fadul\u00f3 csapad\u00e9k al\u00e1mosta r\u00e9zs\u0171 k\u00f6r\u00f6mvonal\u00e1t. Az \u00fatr\u00f3l az \u00e1rokba foly\u00f3 v\u00edz a r\u00e9zs\u0171s mederpartfal m\u00f6g\u00e9","og_url":"https:\/\/dorogimedence.hu\/index.php\/2023\/02\/21\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2023-02-21T09:28:32+00:00","article_modified_time":"2023-02-21T09:28:50+00:00","og_image":[{"width":1369,"height":767,"url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2023\/02\/vaskapui-ut.jpg","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu","Becs\u00fclt olvas\u00e1si id\u0151":"1 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/02\/21\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/02\/21\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"F\u00e9lp\u00e1ly\u00e1s \u00fatlez\u00e1r\u00e1s Esztergomban a Vaskapui \u00faton","datePublished":"2023-02-21T09:28:32+00:00","dateModified":"2023-02-21T09:28:50+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/02\/21\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\/"},"wordCount":281,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/02\/21\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2023\/02\/vaskapui-ut.jpg","keywords":["esztergom","f\u00e9lp\u00e1ly\u00e1s \u00fatlez\u00e1r\u00e1s","\u00fatlez\u00e1r\u00e1s","Vaskapui \u00fat"],"articleSection":["Esztergom","H\u00edrek"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/02\/21\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\/","url":"https:\/\/dorogimedence.hu\/index.php\/2023\/02\/21\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\/","name":"F\u00e9lp\u00e1ly\u00e1s \u00fatlez\u00e1r\u00e1s Esztergomban a Vaskapui \u00faton","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/02\/21\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/02\/21\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2023\/02\/vaskapui-ut.jpg","datePublished":"2023-02-21T09:28:32+00:00","dateModified":"2023-02-21T09:28:50+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/02\/21\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2023\/02\/21\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/02\/21\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2023\/02\/vaskapui-ut.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2023\/02\/vaskapui-ut.jpg","width":1369,"height":767},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2023\/02\/21\/felpalyas-utlezaras-esztergomban-a-vaskapui-uton\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"F\u00e9lp\u00e1ly\u00e1s \u00fatlez\u00e1r\u00e1s Esztergomban a Vaskapui \u00faton"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/50513","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=50513"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/50513\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/50514"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=50513"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=50513"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=50513"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}