{"id":4843,"date":"2017-08-03T08:27:14","date_gmt":"2017-08-03T06:27:14","guid":{"rendered":"http:\/\/dorogimedence.hu\/?p=4843"},"modified":"2017-08-03T08:27:14","modified_gmt":"2017-08-03T06:27:14","slug":"17-sarisapi-virag-es-termenykiallitas","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2017\/08\/03\/17-sarisapi-virag-es-termenykiallitas\/","title":{"rendered":"17. S\u00e1ris\u00e1pi Vir\u00e1g- \u00e9s Term\u00e9nyki\u00e1ll\u00edt\u00e1s"},"content":{"rendered":"<p><strong>Annav\u00f6lgy \u00e9s S\u00e1ris\u00e1p Kertbar\u00e1tainak \u00e9s Borbar\u00e1tn\u0151inek Egyes\u00fclete 17. alkalommal rendezik meg a S\u00e1ris\u00e1pi Vir\u00e1g- \u00e9s Term\u00e9nyki\u00e1ll\u00edt\u00e1st, augusztus 19-\u00e9n \u00e9s 20-\u00e1n.<\/strong><\/p>\n<p>Megk\u00e9rnek minden vir\u00e1got szeret\u0151 \u00e9s kert\u00e9szked\u0151 annav\u00f6lgyi \u00e9s s\u00e1ris\u00e1pi egyes\u00fcleti tagot \u00e9s k\u00edv\u00fcl\u00e1ll\u00f3 lak\u00f3t\u00e1rsat, hogy vegyenek r\u00e9szt min\u00e9l t\u00f6bben saj\u00e1t termeszt\u00e9s\u0171, bemutat\u00e1sra, illetve ki\u00e1ll\u00edt\u00e1sra alkalmas n\u00f6v\u00e9ny-k\u00fcl\u00f6nlegess\u00e9geikkel a hagyom\u00e1ny\u0151rz\u0151 rendezv\u00e9ny sikeres lebonyol\u00edt\u00e1s\u00e1ban!<\/p>\n<p>A ki\u00e1ll\u00edt\u00e1sra sz\u00e1nt t\u00e1rgyakat augusztus 18-\u00e1n p\u00e9ntek 8-16 \u00f3ra k\u00f6z\u00f6tt k\u00e9rik leadni a ki\u00e1ll\u00edt\u00e1s helysz\u00edn\u00e9n, a S\u00e1ris\u00e1pi M\u0171vel\u0151d\u00e9si H\u00e1zban. Hazasz\u00e1ll\u00edt\u00e1sra augusztus 21-\u00e9n, h\u00e9tf\u0151n 8 \u00f3r\u00e1t\u00f3l van lehet\u0151s\u00e9g. A vir\u00e1gok \u00f6nt\u00f6z\u00e9s\u00e9t biztos\u00edtj\u00e1t.<\/p>\n<p><a href=\"http:\/\/www.sarisap.hu\/files\/hirek\/viragkiallitas_2017.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline; color: #0000ff;\"><strong>R\u00e9szeltes inform\u00e1ci\u00f3&gt;&gt;<\/strong><\/span><\/a><\/p>\n<p><a href=\"http:\/\/www.sarisap.hu\/files\/hirek\/legszebb_kert_2017.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline; color: #0000ff;\"><strong>S\u00e1ris\u00e1p legszebb parkos\u00edtott udvara \u00e9s legszebb kertje verseny ki\u00edr\u00e1sa&gt;&gt;<\/strong><\/span><\/a><\/p>\n<p><em>Forr\u00e1s: sarisap.hu<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Annav\u00f6lgy \u00e9s S\u00e1ris\u00e1p Kertbar\u00e1tainak \u00e9s Borbar\u00e1tn\u0151inek Egyes\u00fclete 17. alkalommal rendezik meg a S\u00e1ris\u00e1pi Vir\u00e1g- \u00e9s Term\u00e9nyki\u00e1ll\u00edt\u00e1st, augusztus 19-\u00e9n \u00e9s 20-\u00e1n. Megk\u00e9rnek minden vir\u00e1got szeret\u0151 \u00e9s kert\u00e9szked\u0151 annav\u00f6lgyi \u00e9s s\u00e1ris\u00e1pi egyes\u00fcleti tagot \u00e9s k\u00edv\u00fcl\u00e1ll\u00f3 lak\u00f3t\u00e1rsat, hogy vegyenek r\u00e9szt min\u00e9l t\u00f6bben saj\u00e1t termeszt\u00e9s\u0171, bemutat\u00e1sra, illetve ki\u00e1ll\u00edt\u00e1sra alkalmas n\u00f6v\u00e9ny-k\u00fcl\u00f6nlegess\u00e9geikkel a hagyom\u00e1ny\u0151rz\u0151 rendezv\u00e9ny sikeres lebonyol\u00edt\u00e1s\u00e1ban! A ki\u00e1ll\u00edt\u00e1sra sz\u00e1nt t\u00e1rgyakat<\/p>\n","protected":false},"author":1,"featured_media":4844,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3],"tags":[347,423,1354,1353],"class_list":["post-4843","post","type-post","status-publish","format-standard","has-post-thumbnail","category-hirek","tag-annavolgy","tag-sarisap","tag-termenykiallitas","tag-viragkiallitas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>17. S\u00e1ris\u00e1pi Vir\u00e1g- \u00e9s Term\u00e9nyki\u00e1ll\u00edt\u00e1s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2017\/08\/03\/17-sarisapi-virag-es-termenykiallitas\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"17. S\u00e1ris\u00e1pi Vir\u00e1g- \u00e9s Term\u00e9nyki\u00e1ll\u00edt\u00e1s\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Annav\u00f6lgy \u00e9s S\u00e1ris\u00e1p Kertbar\u00e1tainak \u00e9s Borbar\u00e1tn\u0151inek Egyes\u00fclete 17. alkalommal rendezik meg a S\u00e1ris\u00e1pi Vir\u00e1g- \u00e9s Term\u00e9nyki\u00e1ll\u00edt\u00e1st, augusztus 19-\u00e9n \u00e9s 20-\u00e1n. Megk\u00e9rnek minden vir\u00e1got szeret\u0151 \u00e9s kert\u00e9szked\u0151 annav\u00f6lgyi \u00e9s s\u00e1ris\u00e1pi egyes\u00fcleti tagot \u00e9s k\u00edv\u00fcl\u00e1ll\u00f3 lak\u00f3t\u00e1rsat, hogy vegyenek r\u00e9szt min\u00e9l t\u00f6bben saj\u00e1t termeszt\u00e9s\u0171, bemutat\u00e1sra, illetve ki\u00e1ll\u00edt\u00e1sra alkalmas n\u00f6v\u00e9ny-k\u00fcl\u00f6nlegess\u00e9geikkel a hagyom\u00e1ny\u0151rz\u0151 rendezv\u00e9ny sikeres lebonyol\u00edt\u00e1s\u00e1ban! A ki\u00e1ll\u00edt\u00e1sra sz\u00e1nt t\u00e1rgyakat\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2017\/08\/03\/17-sarisapi-virag-es-termenykiallitas\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-03T06:27:14+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/08\/viragkiallitas.jpg?fit=670%2C365&ssl=1\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 perc\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/08\\\/03\\\/17-sarisapi-virag-es-termenykiallitas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/08\\\/03\\\/17-sarisapi-virag-es-termenykiallitas\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"17. S\u00e1ris\u00e1pi Vir\u00e1g- \u00e9s Term\u00e9nyki\u00e1ll\u00edt\u00e1s\",\"datePublished\":\"2017-08-03T06:27:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/08\\\/03\\\/17-sarisapi-virag-es-termenykiallitas\\\/\"},\"wordCount\":202,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/08\\\/03\\\/17-sarisapi-virag-es-termenykiallitas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/viragkiallitas.jpg\",\"keywords\":[\"Annav\u00f6lgy\",\"S\u00e1ris\u00e1p\",\"term\u00e9nyki\u00e1ll\u00edt\u00e1s\",\"vir\u00e1gki\u00e1ll\u00edt\u00e1s\"],\"articleSection\":[\"H\u00edrek\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/08\\\/03\\\/17-sarisapi-virag-es-termenykiallitas\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/08\\\/03\\\/17-sarisapi-virag-es-termenykiallitas\\\/\",\"name\":\"17. S\u00e1ris\u00e1pi Vir\u00e1g- \u00e9s Term\u00e9nyki\u00e1ll\u00edt\u00e1s\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/08\\\/03\\\/17-sarisapi-virag-es-termenykiallitas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/08\\\/03\\\/17-sarisapi-virag-es-termenykiallitas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/viragkiallitas.jpg\",\"datePublished\":\"2017-08-03T06:27:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/08\\\/03\\\/17-sarisapi-virag-es-termenykiallitas\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/08\\\/03\\\/17-sarisapi-virag-es-termenykiallitas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/08\\\/03\\\/17-sarisapi-virag-es-termenykiallitas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/viragkiallitas.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/viragkiallitas.jpg\",\"width\":670,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/08\\\/03\\\/17-sarisapi-virag-es-termenykiallitas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"17. S\u00e1ris\u00e1pi Vir\u00e1g- \u00e9s Term\u00e9nyki\u00e1ll\u00edt\u00e1s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"17. S\u00e1ris\u00e1pi Vir\u00e1g- \u00e9s Term\u00e9nyki\u00e1ll\u00edt\u00e1s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2017\/08\/03\/17-sarisapi-virag-es-termenykiallitas\/","og_locale":"hu_HU","og_type":"article","og_title":"17. S\u00e1ris\u00e1pi Vir\u00e1g- \u00e9s Term\u00e9nyki\u00e1ll\u00edt\u00e1s","og_description":"Annav\u00f6lgy \u00e9s S\u00e1ris\u00e1p Kertbar\u00e1tainak \u00e9s Borbar\u00e1tn\u0151inek Egyes\u00fclete 17. alkalommal rendezik meg a S\u00e1ris\u00e1pi Vir\u00e1g- \u00e9s Term\u00e9nyki\u00e1ll\u00edt\u00e1st, augusztus 19-\u00e9n \u00e9s 20-\u00e1n. Megk\u00e9rnek minden vir\u00e1got szeret\u0151 \u00e9s kert\u00e9szked\u0151 annav\u00f6lgyi \u00e9s s\u00e1ris\u00e1pi egyes\u00fcleti tagot \u00e9s k\u00edv\u00fcl\u00e1ll\u00f3 lak\u00f3t\u00e1rsat, hogy vegyenek r\u00e9szt min\u00e9l t\u00f6bben saj\u00e1t termeszt\u00e9s\u0171, bemutat\u00e1sra, illetve ki\u00e1ll\u00edt\u00e1sra alkalmas n\u00f6v\u00e9ny-k\u00fcl\u00f6nlegess\u00e9geikkel a hagyom\u00e1ny\u0151rz\u0151 rendezv\u00e9ny sikeres lebonyol\u00edt\u00e1s\u00e1ban! A ki\u00e1ll\u00edt\u00e1sra sz\u00e1nt t\u00e1rgyakat","og_url":"https:\/\/dorogimedence.hu\/index.php\/2017\/08\/03\/17-sarisapi-virag-es-termenykiallitas\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2017-08-03T06:27:14+00:00","og_image":[{"width":670,"height":365,"url":"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/08\/viragkiallitas.jpg?fit=670%2C365&ssl=1","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu","Becs\u00fclt olvas\u00e1si id\u0151":"1 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/08\/03\/17-sarisapi-virag-es-termenykiallitas\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/08\/03\/17-sarisapi-virag-es-termenykiallitas\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"17. S\u00e1ris\u00e1pi Vir\u00e1g- \u00e9s Term\u00e9nyki\u00e1ll\u00edt\u00e1s","datePublished":"2017-08-03T06:27:14+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/08\/03\/17-sarisapi-virag-es-termenykiallitas\/"},"wordCount":202,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/08\/03\/17-sarisapi-virag-es-termenykiallitas\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/08\/viragkiallitas.jpg","keywords":["Annav\u00f6lgy","S\u00e1ris\u00e1p","term\u00e9nyki\u00e1ll\u00edt\u00e1s","vir\u00e1gki\u00e1ll\u00edt\u00e1s"],"articleSection":["H\u00edrek"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/08\/03\/17-sarisapi-virag-es-termenykiallitas\/","url":"https:\/\/dorogimedence.hu\/index.php\/2017\/08\/03\/17-sarisapi-virag-es-termenykiallitas\/","name":"17. S\u00e1ris\u00e1pi Vir\u00e1g- \u00e9s Term\u00e9nyki\u00e1ll\u00edt\u00e1s","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/08\/03\/17-sarisapi-virag-es-termenykiallitas\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/08\/03\/17-sarisapi-virag-es-termenykiallitas\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/08\/viragkiallitas.jpg","datePublished":"2017-08-03T06:27:14+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/08\/03\/17-sarisapi-virag-es-termenykiallitas\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2017\/08\/03\/17-sarisapi-virag-es-termenykiallitas\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/08\/03\/17-sarisapi-virag-es-termenykiallitas\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/08\/viragkiallitas.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/08\/viragkiallitas.jpg","width":670,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/08\/03\/17-sarisapi-virag-es-termenykiallitas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"17. S\u00e1ris\u00e1pi Vir\u00e1g- \u00e9s Term\u00e9nyki\u00e1ll\u00edt\u00e1s"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/4843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=4843"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/4843\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/4844"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=4843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=4843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=4843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}