{"id":4592,"date":"2017-07-22T07:16:40","date_gmt":"2017-07-22T05:16:40","guid":{"rendered":"http:\/\/dorogimedence.hu\/?p=4592"},"modified":"2017-07-22T07:16:40","modified_gmt":"2017-07-22T05:16:40","slug":"sebessegellenorzesek-julius-22-29","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2017\/07\/22\/sebessegellenorzesek-julius-22-29\/","title":{"rendered":"Sebess\u00e9gellen\u0151rz\u00e9sek: j\u00falius 22-29."},"content":{"rendered":"<p><strong>Dorog \u00e9s k\u00f6rny\u00e9ken ism\u00e9t t\u00f6bb helyen sz\u00e1m\u00edthatunk sebess\u00e9gellen\u0151rz\u00e9sekre j\u00falius 22-e \u00e9s 29-e k\u00f6z\u00f6tt. Az al\u00e1bbiakban kigy\u0171jt\u00f6tt\u00fck a m\u00e9r\u0151helyeket \u00e9s az id\u0151pontokat.<\/strong><\/p>\n<p><span style=\"text-decoration: underline;\"><strong>J\u00falius 22. szombat<\/strong><\/span><br \/>\n09.00-19.00 Nyerges\u00fajfalu, L\u00e1batlan, S\u00fctt\u0151 10. sz. f\u0151\u00fat<br \/>\n01.00-03.00 117. sz. f\u0151\u00fat 1+500 kmsz., Keszt\u00f6lc k\u00fclter\u00fclet<br \/>\n03.00-05.00 Dorog, B\u00e9csi u. 112.<br \/>\n09.00-11.00 Dorog, B\u00e9csi u. 112.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>J\u00falius 23. vas\u00e1rnap<\/strong><\/span><br \/>\n09.00-19.00 T\u00e1t, Esztergom belter\u00fclet 10. sz., 11. sz. f\u0151\u00fat<br \/>\n01.00-03.00 117. sz. f\u0151\u00fat 1+500 kmsz., Keszt\u00f6lc k\u00fclter\u00fclet<br \/>\n03.00-05.00 Le\u00e1nyv\u00e1r, B\u00e9csi u. 72.<br \/>\n09.00-11.00 Dorog, B\u00e9csi u. 112.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>J\u00falius 24. h\u00e9tf\u0151<\/strong><\/span><br \/>\n09.00-19.00 Esztergom belter\u00fclet 11. sz. f\u0151\u00fat<br \/>\n01.00-03.00 Dorog, B\u00e9csi u. 112.<br \/>\n03.00-05.00 Le\u00e1nyv\u00e1r, B\u00e9csi u. 72.<br \/>\n09.00-11.00 Dorog, B\u00e9csi u. 112.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>J\u00falius 25. kedd<\/strong><\/span><br \/>\n09.00-19.00 D\u00f6m\u00f6s, Pilismar\u00f3t, Esztergom belter\u00fclet, 11. sz. f\u0151\u00fat<br \/>\n01.00-03.00 117. sz. f\u0151\u00fat 1+500 kmsz., Keszt\u00f6lc k\u00fclter\u00fclet<br \/>\n03.00-05.00 Dorog, B\u00e9csi u. 112.<br \/>\n09.00-11.00 Dorog, B\u00e9csi u. 112.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>J\u00falius 26. szerda<\/strong><\/span><br \/>\n09.00-19.00 D\u00f6m\u00f6s, Pilismar\u00f3t, Esztergom belter\u00fclet, 11. sz. f\u0151\u00fat<br \/>\n01.00-03.00 Le\u00e1nyv\u00e1r, B\u00e9csi u. 72.<br \/>\n03.00-05.00 Dorog, B\u00e9csi u. 112.<br \/>\n09.00-11.00 Dorog, B\u00e9csi u. 112.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>J\u00falius 27. cs\u00fct\u00f6rt\u00f6k<\/strong><\/span><br \/>\n09.00-19.00 D\u00f6m\u00f6s, Pilismar\u00f3t, Esztergom belter\u00fclet, 11. sz. f\u0151\u00fat<br \/>\n01.00-03.00 117. sz. f\u0151\u00fat 1+500 kmsz., Keszt\u00f6lc k\u00fclter\u00fclet<br \/>\n03.00-05.00 Le\u00e1nyv\u00e1r, B\u00e9csi u. 72.<br \/>\n09.00-11.00 Dorog, B\u00e9csi u. 112.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>J\u00falius 28. p\u00e9ntek<\/strong><\/span><br \/>\n09.00-19.00 Nyerges\u00fajfalu, L\u00e1batlan, S\u00fctt\u0151 10. sz. f\u0151\u00fat<br \/>\n01.00-03.00 Dorog, B\u00e9csi u. 112.<br \/>\n03.00-05.00 Le\u00e1nyv\u00e1r, B\u00e9csi u. 72.<br \/>\n09.00-11.00 Dorog, B\u00e9csi u. 112.<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>J\u00falius 29. szombat<\/strong><\/span><br \/>\n09.00-19.00 D\u00f6m\u00f6s, Pilismar\u00f3t, Esztergom belter\u00fclet, 11. sz. f\u0151\u00fat<br \/>\n01.00-03.00 117. sz. f\u0151\u00fat 1+500 kmsz., Keszt\u00f6lc k\u00fclter\u00fclet<br \/>\n03.00-05.00 Le\u00e1nyv\u00e1r, B\u00e9csi u. 72.<br \/>\n09.00-11.00 Dorog, B\u00e9csi u. 112.<\/p>\n<p><strong><em>A sebess\u00e9g ellen\u0151rz\u00e9seken k\u00edv\u00fcli id\u0151pontokban is \u00f3vatosan vezessenek!<\/em><\/strong><\/p>\n<p><em>Forr\u00e1s: police.hu<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dorog \u00e9s k\u00f6rny\u00e9ken ism\u00e9t t\u00f6bb helyen sz\u00e1m\u00edthatunk sebess\u00e9gellen\u0151rz\u00e9sekre j\u00falius 22-e \u00e9s 29-e k\u00f6z\u00f6tt. Az al\u00e1bbiakban kigy\u0171jt\u00f6tt\u00fck a m\u00e9r\u0151helyeket \u00e9s az id\u0151pontokat. J\u00falius 22. szombat 09.00-19.00 Nyerges\u00fajfalu, L\u00e1batlan, S\u00fctt\u0151 10. sz. f\u0151\u00fat 01.00-03.00 117. sz. f\u0151\u00fat 1+500 kmsz., Keszt\u00f6lc k\u00fclter\u00fclet 03.00-05.00 Dorog, B\u00e9csi u. 112. 09.00-11.00 Dorog, B\u00e9csi u. 112. J\u00falius 23. vas\u00e1rnap 09.00-19.00 T\u00e1t, Esztergom<\/p>\n","protected":false},"author":1,"featured_media":4436,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[2,38,3,8,9,110],"tags":[279,61,387,93],"class_list":{"0":"post-4592","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dorog","8":"category-esztergom","9":"category-hirek","10":"category-kesztolc","11":"category-leanyvar","12":"category-tat","13":"tag-kozlekedes","14":"tag-rendorsegi-hirek","15":"tag-sebessegellenorzesek","16":"tag-traffipax"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sebess\u00e9gellen\u0151rz\u00e9sek: j\u00falius 22-29.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2017\/07\/22\/sebessegellenorzesek-julius-22-29\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Sebess\u00e9gellen\u0151rz\u00e9sek: j\u00falius 22-29.\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Dorog \u00e9s k\u00f6rny\u00e9ken ism\u00e9t t\u00f6bb helyen sz\u00e1m\u00edthatunk sebess\u00e9gellen\u0151rz\u00e9sekre j\u00falius 22-e \u00e9s 29-e k\u00f6z\u00f6tt. Az al\u00e1bbiakban kigy\u0171jt\u00f6tt\u00fck a m\u00e9r\u0151helyeket \u00e9s az id\u0151pontokat. J\u00falius 22. szombat 09.00-19.00 Nyerges\u00fajfalu, L\u00e1batlan, S\u00fctt\u0151 10. sz. f\u0151\u00fat 01.00-03.00 117. sz. f\u0151\u00fat 1+500 kmsz., Keszt\u00f6lc k\u00fclter\u00fclet 03.00-05.00 Dorog, B\u00e9csi u. 112. 09.00-11.00 Dorog, B\u00e9csi u. 112. J\u00falius 23. vas\u00e1rnap 09.00-19.00 T\u00e1t, Esztergom\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2017\/07\/22\/sebessegellenorzesek-julius-22-29\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-22T05:16:40+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/07\/traffi5-1.jpg?fit=670%2C365&ssl=1\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 perc\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/07\\\/22\\\/sebessegellenorzesek-julius-22-29\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/07\\\/22\\\/sebessegellenorzesek-julius-22-29\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"Sebess\u00e9gellen\u0151rz\u00e9sek: j\u00falius 22-29.\",\"datePublished\":\"2017-07-22T05:16:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/07\\\/22\\\/sebessegellenorzesek-julius-22-29\\\/\"},\"wordCount\":337,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/07\\\/22\\\/sebessegellenorzesek-julius-22-29\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/traffi5-1.jpg\",\"keywords\":[\"k\u00f6zleked\u00e9s\",\"rend\u0151rs\u00e9gi h\u00edrek\",\"sebess\u00e9gellen\u0151rz\u00e9sek\",\"traffipax\"],\"articleSection\":[\"Dorog\",\"Esztergom\",\"H\u00edrek\",\"Keszt\u00f6lc\",\"Le\u00e1nyv\u00e1r\",\"T\u00e1t\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/07\\\/22\\\/sebessegellenorzesek-julius-22-29\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/07\\\/22\\\/sebessegellenorzesek-julius-22-29\\\/\",\"name\":\"Sebess\u00e9gellen\u0151rz\u00e9sek: j\u00falius 22-29.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/07\\\/22\\\/sebessegellenorzesek-julius-22-29\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/07\\\/22\\\/sebessegellenorzesek-julius-22-29\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/traffi5-1.jpg\",\"datePublished\":\"2017-07-22T05:16:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/07\\\/22\\\/sebessegellenorzesek-julius-22-29\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/07\\\/22\\\/sebessegellenorzesek-julius-22-29\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/07\\\/22\\\/sebessegellenorzesek-julius-22-29\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/traffi5-1.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/traffi5-1.jpg\",\"width\":670,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/07\\\/22\\\/sebessegellenorzesek-julius-22-29\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sebess\u00e9gellen\u0151rz\u00e9sek: j\u00falius 22-29.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sebess\u00e9gellen\u0151rz\u00e9sek: j\u00falius 22-29.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2017\/07\/22\/sebessegellenorzesek-julius-22-29\/","og_locale":"hu_HU","og_type":"article","og_title":"Sebess\u00e9gellen\u0151rz\u00e9sek: j\u00falius 22-29.","og_description":"Dorog \u00e9s k\u00f6rny\u00e9ken ism\u00e9t t\u00f6bb helyen sz\u00e1m\u00edthatunk sebess\u00e9gellen\u0151rz\u00e9sekre j\u00falius 22-e \u00e9s 29-e k\u00f6z\u00f6tt. Az al\u00e1bbiakban kigy\u0171jt\u00f6tt\u00fck a m\u00e9r\u0151helyeket \u00e9s az id\u0151pontokat. J\u00falius 22. szombat 09.00-19.00 Nyerges\u00fajfalu, L\u00e1batlan, S\u00fctt\u0151 10. sz. f\u0151\u00fat 01.00-03.00 117. sz. f\u0151\u00fat 1+500 kmsz., Keszt\u00f6lc k\u00fclter\u00fclet 03.00-05.00 Dorog, B\u00e9csi u. 112. 09.00-11.00 Dorog, B\u00e9csi u. 112. J\u00falius 23. vas\u00e1rnap 09.00-19.00 T\u00e1t, Esztergom","og_url":"https:\/\/dorogimedence.hu\/index.php\/2017\/07\/22\/sebessegellenorzesek-julius-22-29\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2017-07-22T05:16:40+00:00","og_image":[{"width":670,"height":365,"url":"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/07\/traffi5-1.jpg?fit=670%2C365&ssl=1","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu","Becs\u00fclt olvas\u00e1si id\u0151":"2 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/07\/22\/sebessegellenorzesek-julius-22-29\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/07\/22\/sebessegellenorzesek-julius-22-29\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"Sebess\u00e9gellen\u0151rz\u00e9sek: j\u00falius 22-29.","datePublished":"2017-07-22T05:16:40+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/07\/22\/sebessegellenorzesek-julius-22-29\/"},"wordCount":337,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/07\/22\/sebessegellenorzesek-julius-22-29\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/07\/traffi5-1.jpg","keywords":["k\u00f6zleked\u00e9s","rend\u0151rs\u00e9gi h\u00edrek","sebess\u00e9gellen\u0151rz\u00e9sek","traffipax"],"articleSection":["Dorog","Esztergom","H\u00edrek","Keszt\u00f6lc","Le\u00e1nyv\u00e1r","T\u00e1t"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/07\/22\/sebessegellenorzesek-julius-22-29\/","url":"https:\/\/dorogimedence.hu\/index.php\/2017\/07\/22\/sebessegellenorzesek-julius-22-29\/","name":"Sebess\u00e9gellen\u0151rz\u00e9sek: j\u00falius 22-29.","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/07\/22\/sebessegellenorzesek-julius-22-29\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/07\/22\/sebessegellenorzesek-julius-22-29\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/07\/traffi5-1.jpg","datePublished":"2017-07-22T05:16:40+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/07\/22\/sebessegellenorzesek-julius-22-29\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2017\/07\/22\/sebessegellenorzesek-julius-22-29\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/07\/22\/sebessegellenorzesek-julius-22-29\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/07\/traffi5-1.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/07\/traffi5-1.jpg","width":670,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/07\/22\/sebessegellenorzesek-julius-22-29\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"Sebess\u00e9gellen\u0151rz\u00e9sek: j\u00falius 22-29."}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/4592","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=4592"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/4592\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/4436"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=4592"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=4592"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=4592"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}