{"id":30770,"date":"2021-03-02T09:05:10","date_gmt":"2021-03-02T08:05:10","guid":{"rendered":"http:\/\/dorogimedence.hu\/?p=30770"},"modified":"2021-03-02T09:05:43","modified_gmt":"2021-03-02T08:05:43","slug":"korozott-ferfit-fogtak-el-labatlanon-2","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2021\/03\/02\/korozott-ferfit-fogtak-el-labatlanon-2\/","title":{"rendered":"K\u00f6r\u00f6z\u00f6tt f\u00e9rfit fogtak el L\u00e1batlanon"},"content":{"rendered":"<div class=\"item_introtext\">\n<p><strong>M\u00e1rcius 1-j\u00e9n, h\u00e9tf\u0151 d\u00e9lut\u00e1n egy k\u00f6r\u00f6z\u00f6tt szem\u00e9lyt fogtak el a rend\u0151r\u00f6k L\u00e1batlanon.<\/strong><\/p>\n<\/div>\n<div class=\"item_fulltext\">\n<p>A helyi j\u00e1r\u0151r\u00f6k a R\u00e1k\u00f3czi Ferenc \u00faton ellen\u0151rizt\u00e9k azt a helyi lakost, aki ellen a Tatab\u00e1nyai T\u00f6rv\u00e9nysz\u00e9k elfogat\u00f3parancsot bocs\u00e1tott ki. Az egyenruh\u00e1sok a 23 \u00e9ves f\u00e9rfit a rend\u0151rkapit\u00e1nys\u00e1gra el\u0151\u00e1ll\u00edtott\u00e1k, ahol \u0151rizetbe vett\u00e9k.<\/p>\n<p><em>Forr\u00e1s: police.hu<\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1rcius 1-j\u00e9n, h\u00e9tf\u0151 d\u00e9lut\u00e1n egy k\u00f6r\u00f6z\u00f6tt szem\u00e9lyt fogtak el a rend\u0151r\u00f6k L\u00e1batlanon. A helyi j\u00e1r\u0151r\u00f6k a R\u00e1k\u00f3czi Ferenc \u00faton ellen\u0151rizt\u00e9k azt a helyi lakost, aki ellen a Tatab\u00e1nyai T\u00f6rv\u00e9nysz\u00e9k elfogat\u00f3parancsot bocs\u00e1tott ki. Az egyenruh\u00e1sok a 23 \u00e9ves f\u00e9rfit a rend\u0151rkapit\u00e1nys\u00e1gra el\u0151\u00e1ll\u00edtott\u00e1k, ahol \u0151rizetbe vett\u00e9k. Forr\u00e1s: police.hu<\/p>\n","protected":false},"author":1,"featured_media":3653,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,39],"tags":[1556,106,489,61],"class_list":{"0":"post-30770","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-hirek","8":"category-kek-hirek","9":"tag-elfogatoparancs","10":"tag-korozes","11":"tag-labatlan","12":"tag-rendorsegi-hirek"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>K\u00f6r\u00f6z\u00f6tt f\u00e9rfit fogtak el L\u00e1batlanon<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2021\/03\/02\/korozott-ferfit-fogtak-el-labatlanon-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"K\u00f6r\u00f6z\u00f6tt f\u00e9rfit fogtak el L\u00e1batlanon\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"M\u00e1rcius 1-j\u00e9n, h\u00e9tf\u0151 d\u00e9lut\u00e1n egy k\u00f6r\u00f6z\u00f6tt szem\u00e9lyt fogtak el a rend\u0151r\u00f6k L\u00e1batlanon. A helyi j\u00e1r\u0151r\u00f6k a R\u00e1k\u00f3czi Ferenc \u00faton ellen\u0151rizt\u00e9k azt a helyi lakost, aki ellen a Tatab\u00e1nyai T\u00f6rv\u00e9nysz\u00e9k elfogat\u00f3parancsot bocs\u00e1tott ki. Az egyenruh\u00e1sok a 23 \u00e9ves f\u00e9rfit a rend\u0151rkapit\u00e1nys\u00e1gra el\u0151\u00e1ll\u00edtott\u00e1k, ahol \u0151rizetbe vett\u00e9k. Forr\u00e1s: police.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2021\/03\/02\/korozott-ferfit-fogtak-el-labatlanon-2\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-02T08:05:10+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-02T08:05:43+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/06\/bilincs03.jpg?fit=670%2C365&ssl=1\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2021\\\/03\\\/02\\\/korozott-ferfit-fogtak-el-labatlanon-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2021\\\/03\\\/02\\\/korozott-ferfit-fogtak-el-labatlanon-2\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"K\u00f6r\u00f6z\u00f6tt f\u00e9rfit fogtak el L\u00e1batlanon\",\"datePublished\":\"2021-03-02T08:05:10+00:00\",\"dateModified\":\"2021-03-02T08:05:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2021\\\/03\\\/02\\\/korozott-ferfit-fogtak-el-labatlanon-2\\\/\"},\"wordCount\":91,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2021\\\/03\\\/02\\\/korozott-ferfit-fogtak-el-labatlanon-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/bilincs03.jpg\",\"keywords\":[\"elfogat\u00f3parancs\",\"k\u00f6r\u00f6z\u00e9s\",\"L\u00e1batlan\",\"rend\u0151rs\u00e9gi h\u00edrek\"],\"articleSection\":[\"H\u00edrek\",\"K\u00e9k h\u00edrek\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2021\\\/03\\\/02\\\/korozott-ferfit-fogtak-el-labatlanon-2\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2021\\\/03\\\/02\\\/korozott-ferfit-fogtak-el-labatlanon-2\\\/\",\"name\":\"K\u00f6r\u00f6z\u00f6tt f\u00e9rfit fogtak el L\u00e1batlanon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2021\\\/03\\\/02\\\/korozott-ferfit-fogtak-el-labatlanon-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2021\\\/03\\\/02\\\/korozott-ferfit-fogtak-el-labatlanon-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/bilincs03.jpg\",\"datePublished\":\"2021-03-02T08:05:10+00:00\",\"dateModified\":\"2021-03-02T08:05:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2021\\\/03\\\/02\\\/korozott-ferfit-fogtak-el-labatlanon-2\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2021\\\/03\\\/02\\\/korozott-ferfit-fogtak-el-labatlanon-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2021\\\/03\\\/02\\\/korozott-ferfit-fogtak-el-labatlanon-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/bilincs03.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/06\\\/bilincs03.jpg\",\"width\":670,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2021\\\/03\\\/02\\\/korozott-ferfit-fogtak-el-labatlanon-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"K\u00f6r\u00f6z\u00f6tt f\u00e9rfit fogtak el L\u00e1batlanon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"K\u00f6r\u00f6z\u00f6tt f\u00e9rfit fogtak el L\u00e1batlanon","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2021\/03\/02\/korozott-ferfit-fogtak-el-labatlanon-2\/","og_locale":"hu_HU","og_type":"article","og_title":"K\u00f6r\u00f6z\u00f6tt f\u00e9rfit fogtak el L\u00e1batlanon","og_description":"M\u00e1rcius 1-j\u00e9n, h\u00e9tf\u0151 d\u00e9lut\u00e1n egy k\u00f6r\u00f6z\u00f6tt szem\u00e9lyt fogtak el a rend\u0151r\u00f6k L\u00e1batlanon. A helyi j\u00e1r\u0151r\u00f6k a R\u00e1k\u00f3czi Ferenc \u00faton ellen\u0151rizt\u00e9k azt a helyi lakost, aki ellen a Tatab\u00e1nyai T\u00f6rv\u00e9nysz\u00e9k elfogat\u00f3parancsot bocs\u00e1tott ki. Az egyenruh\u00e1sok a 23 \u00e9ves f\u00e9rfit a rend\u0151rkapit\u00e1nys\u00e1gra el\u0151\u00e1ll\u00edtott\u00e1k, ahol \u0151rizetbe vett\u00e9k. Forr\u00e1s: police.hu","og_url":"https:\/\/dorogimedence.hu\/index.php\/2021\/03\/02\/korozott-ferfit-fogtak-el-labatlanon-2\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2021-03-02T08:05:10+00:00","article_modified_time":"2021-03-02T08:05:43+00:00","og_image":[{"width":670,"height":365,"url":"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/06\/bilincs03.jpg?fit=670%2C365&ssl=1","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2021\/03\/02\/korozott-ferfit-fogtak-el-labatlanon-2\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2021\/03\/02\/korozott-ferfit-fogtak-el-labatlanon-2\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"K\u00f6r\u00f6z\u00f6tt f\u00e9rfit fogtak el L\u00e1batlanon","datePublished":"2021-03-02T08:05:10+00:00","dateModified":"2021-03-02T08:05:43+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2021\/03\/02\/korozott-ferfit-fogtak-el-labatlanon-2\/"},"wordCount":91,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2021\/03\/02\/korozott-ferfit-fogtak-el-labatlanon-2\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/06\/bilincs03.jpg","keywords":["elfogat\u00f3parancs","k\u00f6r\u00f6z\u00e9s","L\u00e1batlan","rend\u0151rs\u00e9gi h\u00edrek"],"articleSection":["H\u00edrek","K\u00e9k h\u00edrek"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2021\/03\/02\/korozott-ferfit-fogtak-el-labatlanon-2\/","url":"https:\/\/dorogimedence.hu\/index.php\/2021\/03\/02\/korozott-ferfit-fogtak-el-labatlanon-2\/","name":"K\u00f6r\u00f6z\u00f6tt f\u00e9rfit fogtak el L\u00e1batlanon","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2021\/03\/02\/korozott-ferfit-fogtak-el-labatlanon-2\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2021\/03\/02\/korozott-ferfit-fogtak-el-labatlanon-2\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/06\/bilincs03.jpg","datePublished":"2021-03-02T08:05:10+00:00","dateModified":"2021-03-02T08:05:43+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2021\/03\/02\/korozott-ferfit-fogtak-el-labatlanon-2\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2021\/03\/02\/korozott-ferfit-fogtak-el-labatlanon-2\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2021\/03\/02\/korozott-ferfit-fogtak-el-labatlanon-2\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/06\/bilincs03.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/06\/bilincs03.jpg","width":670,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2021\/03\/02\/korozott-ferfit-fogtak-el-labatlanon-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"K\u00f6r\u00f6z\u00f6tt f\u00e9rfit fogtak el L\u00e1batlanon"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/30770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=30770"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/30770\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/3653"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=30770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=30770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=30770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}