{"id":24067,"date":"2020-04-02T17:03:22","date_gmt":"2020-04-02T15:03:22","guid":{"rendered":"http:\/\/dorogimedence.hu\/?p=24067"},"modified":"2020-04-02T17:03:36","modified_gmt":"2020-04-02T15:03:36","slug":"hatszor-lopott-ugyanabbol-a-dorogi-uzletbol","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2020\/04\/02\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\/","title":{"rendered":"Hatszor lopott ugyanabb\u00f3l a dorogi \u00fczletb\u0151l"},"content":{"rendered":"<div class=\"lead-text\">\n<p><strong>A dorogi nyomoz\u00f3k egy 34 \u00e9ves esztergomi f\u00e9rfit hallgattak ki gyan\u00fas\u00edtottk\u00e9nt, aki rendszeresen lopott kozmetikai term\u00e9keket \u00e9s illatszereket.<\/strong><\/p>\n<div class=\"body-text\">\n<p>A gyan\u00fa szerint M. Roland 2020. febru\u00e1r h\u00f3napban n\u00e9gy alkalommal, \u00e9s m\u00e1rcius h\u00f3napban is k\u00e9t alkalommal lopott kozmetikai term\u00e9keket \u00e9s illatszereket ugyanabb\u00f3l a dorogi \u00fczletb\u0151l. A s\u00e9rtett m\u00e1rcius 6-\u00e1n tett feljelent\u00e9st a lop\u00e1sok miatt a Dorogi Rend\u0151rkapit\u00e1nys\u00e1gon. A nyomoz\u00f3k adatgy\u0171jt\u00e9st k\u00f6vet\u0151en azonos\u00edtott\u00e1k a 34 \u00e9ves esztergomi f\u00e9rfit, akit gyan\u00fas\u00edtottk\u00e9nt kihallgattak. Ellene \u00fczletszer\u0171en elk\u00f6vetett lop\u00e1s b\u0171ntett elk\u00f6vet\u00e9se miatt indult b\u00fcntet\u0151elj\u00e1r\u00e1s. A tettes a b\u0171ncselekm\u00e9nyek elk\u00f6vet\u00e9s\u00e9t beismerte.<\/p>\n<p><em>Forr\u00e1s: police.hu<br \/>\nFot\u00f3: illusztr\u00e1ci\u00f3<\/em><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A dorogi nyomoz\u00f3k egy 34 \u00e9ves esztergomi f\u00e9rfit hallgattak ki gyan\u00fas\u00edtottk\u00e9nt, aki rendszeresen lopott kozmetikai term\u00e9keket \u00e9s illatszereket. A gyan\u00fa szerint M. Roland 2020. febru\u00e1r h\u00f3napban n\u00e9gy alkalommal, \u00e9s m\u00e1rcius h\u00f3napban is k\u00e9t alkalommal lopott kozmetikai term\u00e9keket \u00e9s illatszereket ugyanabb\u00f3l a dorogi \u00fczletb\u0151l. A s\u00e9rtett m\u00e1rcius 6-\u00e1n tett feljelent\u00e9st a lop\u00e1sok miatt a Dorogi Rend\u0151rkapit\u00e1nys\u00e1gon.<\/p>\n","protected":false},"author":1,"featured_media":3046,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[2,38,3,39],"tags":[15,42,447,61],"class_list":["post-24067","post","type-post","status-publish","format-standard","has-post-thumbnail","category-dorog","category-esztergom","category-hirek","category-kek-hirek","tag-dorog","tag-esztergom","tag-lopas","tag-rendorsegi-hirek"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hatszor lopott ugyanabb\u00f3l a dorogi \u00fczletb\u0151l<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2020\/04\/02\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Hatszor lopott ugyanabb\u00f3l a dorogi \u00fczletb\u0151l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"A dorogi nyomoz\u00f3k egy 34 \u00e9ves esztergomi f\u00e9rfit hallgattak ki gyan\u00fas\u00edtottk\u00e9nt, aki rendszeresen lopott kozmetikai term\u00e9keket \u00e9s illatszereket. A gyan\u00fa szerint M. Roland 2020. febru\u00e1r h\u00f3napban n\u00e9gy alkalommal, \u00e9s m\u00e1rcius h\u00f3napban is k\u00e9t alkalommal lopott kozmetikai term\u00e9keket \u00e9s illatszereket ugyanabb\u00f3l a dorogi \u00fczletb\u0151l. A s\u00e9rtett m\u00e1rcius 6-\u00e1n tett feljelent\u00e9st a lop\u00e1sok miatt a Dorogi Rend\u0151rkapit\u00e1nys\u00e1gon.\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2020\/04\/02\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-02T15:03:22+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-02T15:03:36+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/05\/lopas-01.jpg?fit=670%2C365&ssl=1\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 perc\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2020\\\/04\\\/02\\\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2020\\\/04\\\/02\\\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"Hatszor lopott ugyanabb\u00f3l a dorogi \u00fczletb\u0151l\",\"datePublished\":\"2020-04-02T15:03:22+00:00\",\"dateModified\":\"2020-04-02T15:03:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2020\\\/04\\\/02\\\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\\\/\"},\"wordCount\":144,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2020\\\/04\\\/02\\\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/lopas-01.jpg\",\"keywords\":[\"Dorog\",\"esztergom\",\"lop\u00e1s\",\"rend\u0151rs\u00e9gi h\u00edrek\"],\"articleSection\":[\"Dorog\",\"Esztergom\",\"H\u00edrek\",\"K\u00e9k h\u00edrek\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2020\\\/04\\\/02\\\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2020\\\/04\\\/02\\\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\\\/\",\"name\":\"Hatszor lopott ugyanabb\u00f3l a dorogi \u00fczletb\u0151l\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2020\\\/04\\\/02\\\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2020\\\/04\\\/02\\\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/lopas-01.jpg\",\"datePublished\":\"2020-04-02T15:03:22+00:00\",\"dateModified\":\"2020-04-02T15:03:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2020\\\/04\\\/02\\\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2020\\\/04\\\/02\\\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2020\\\/04\\\/02\\\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/lopas-01.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/05\\\/lopas-01.jpg\",\"width\":670,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2020\\\/04\\\/02\\\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hatszor lopott ugyanabb\u00f3l a dorogi \u00fczletb\u0151l\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hatszor lopott ugyanabb\u00f3l a dorogi \u00fczletb\u0151l","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2020\/04\/02\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\/","og_locale":"hu_HU","og_type":"article","og_title":"Hatszor lopott ugyanabb\u00f3l a dorogi \u00fczletb\u0151l","og_description":"A dorogi nyomoz\u00f3k egy 34 \u00e9ves esztergomi f\u00e9rfit hallgattak ki gyan\u00fas\u00edtottk\u00e9nt, aki rendszeresen lopott kozmetikai term\u00e9keket \u00e9s illatszereket. A gyan\u00fa szerint M. Roland 2020. febru\u00e1r h\u00f3napban n\u00e9gy alkalommal, \u00e9s m\u00e1rcius h\u00f3napban is k\u00e9t alkalommal lopott kozmetikai term\u00e9keket \u00e9s illatszereket ugyanabb\u00f3l a dorogi \u00fczletb\u0151l. A s\u00e9rtett m\u00e1rcius 6-\u00e1n tett feljelent\u00e9st a lop\u00e1sok miatt a Dorogi Rend\u0151rkapit\u00e1nys\u00e1gon.","og_url":"https:\/\/dorogimedence.hu\/index.php\/2020\/04\/02\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2020-04-02T15:03:22+00:00","article_modified_time":"2020-04-02T15:03:36+00:00","og_image":[{"width":670,"height":365,"url":"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/05\/lopas-01.jpg?fit=670%2C365&ssl=1","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu","Becs\u00fclt olvas\u00e1si id\u0151":"1 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2020\/04\/02\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2020\/04\/02\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"Hatszor lopott ugyanabb\u00f3l a dorogi \u00fczletb\u0151l","datePublished":"2020-04-02T15:03:22+00:00","dateModified":"2020-04-02T15:03:36+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2020\/04\/02\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\/"},"wordCount":144,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2020\/04\/02\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/05\/lopas-01.jpg","keywords":["Dorog","esztergom","lop\u00e1s","rend\u0151rs\u00e9gi h\u00edrek"],"articleSection":["Dorog","Esztergom","H\u00edrek","K\u00e9k h\u00edrek"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2020\/04\/02\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\/","url":"https:\/\/dorogimedence.hu\/index.php\/2020\/04\/02\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\/","name":"Hatszor lopott ugyanabb\u00f3l a dorogi \u00fczletb\u0151l","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2020\/04\/02\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2020\/04\/02\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/05\/lopas-01.jpg","datePublished":"2020-04-02T15:03:22+00:00","dateModified":"2020-04-02T15:03:36+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2020\/04\/02\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2020\/04\/02\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2020\/04\/02\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/05\/lopas-01.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/05\/lopas-01.jpg","width":670,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2020\/04\/02\/hatszor-lopott-ugyanabbol-a-dorogi-uzletbol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"Hatszor lopott ugyanabb\u00f3l a dorogi \u00fczletb\u0151l"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/24067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=24067"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/24067\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/3046"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=24067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=24067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=24067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}