{"id":18941,"date":"2019-08-25T20:42:34","date_gmt":"2019-08-25T18:42:34","guid":{"rendered":"http:\/\/dorogimedence.hu\/?p=18941"},"modified":"2019-08-25T20:55:07","modified_gmt":"2019-08-25T18:55:07","slug":"ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2019\/08\/25\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\/","title":{"rendered":"K\u00e9t esethez is riasztott\u00e1k a t\u0171zolt\u00f3kat vas\u00e1rnap d\u00e9lut\u00e1n"},"content":{"rendered":"<p><strong>K\u00e9t helyre is riasztott\u00e1k a tokodi \u00f6nk\u00e9nteseket, a vas\u00e1rnap d\u00e9lut\u00e1ni kedvez\u0151tlen id\u0151j\u00e1r\u00e1s okozta k\u00e1rok miatt.<\/strong><\/p>\n<p>El\u0151sz\u00f6r egy tokodi csal\u00e1di h\u00e1zhoz kaptak riaszt\u00e1st, ahol a hirtelen lez\u00fadul\u00f3 csapad\u00e9kot az es\u0151csatorna nem tudta elvezetni \u00e9s befolyt a lak\u00e1sba. A tokodi \u00f6nk\u00e9ntesek az esztergomi hivat\u00e1sos t\u0171zolt\u00f3kkal egy\u00fctt szivatty\u00fak seg\u00edts\u00e9g\u00e9vel t\u00e1vol\u00edtott\u00e1k el a vizet a lak\u00e1sb\u00f3l.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-18943\" src=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2019\/08\/viharkar-02.jpg\" alt=\"\" width=\"670\" height=\"499\" srcset=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2019\/08\/viharkar-02.jpg 670w, https:\/\/dorogimedence.hu\/wp-content\/uploads\/2019\/08\/viharkar-02-300x223.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/p>\n<p>A tokodiak miut\u00e1n vissza\u00e9rkeztek a szert\u00e1rba, kapt\u00e1k is a k\u00f6vetkez\u0151 riaszt\u00e1st. Ebsz\u0151nyb\u00e1ny\u00e1n egy fa\u00e1g szakadt le az \u00fattestre, amely forgalmi akad\u00e1lyt k\u00e9pzett. Az eset sor\u00e1n a tokodi \u00f6nk\u00e9ntesek mellett a nyerges\u00fajfalui t\u0171zolt\u00f3k t\u00e1vol\u00edtott\u00e1k el a leszakadt fa\u00e1gat az \u00fattestr\u0151l.<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-18944\" src=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2019\/08\/viharkar-03.jpg\" alt=\"\" width=\"670\" height=\"503\" srcset=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2019\/08\/viharkar-03.jpg 670w, https:\/\/dorogimedence.hu\/wp-content\/uploads\/2019\/08\/viharkar-03-300x225.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/p>\n<p>Mindezek mellett m\u00e9gegy leszakadt fa\u00e1g torlaszolta el az \u00fattestet Tokodon. Err\u0151l \u00e9rtes\u00edt\u00e9st a t\u0171zolt\u00f3k nem kaptak, a lakoss\u00e1g \u00f6sszefog\u00e1ssal oldotta meg az esetet:<\/p>\n<p><iframe style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/post.php?href=https%3A%2F%2Fwww.facebook.com%2Fjulianna.resszerne%2Fposts%2F2449354935156633&amp;width=500\" scrolling=\"no\" width=\"500\" height=\"650\" frameborder=\"0\"><\/iframe><\/p>\n<p><em>Fot\u00f3k: Tokod \u00d6TE<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>K\u00e9t helyre is riasztott\u00e1k a tokodi \u00f6nk\u00e9nteseket, a vas\u00e1rnap d\u00e9lut\u00e1ni kedvez\u0151tlen id\u0151j\u00e1r\u00e1s okozta k\u00e1rok miatt. El\u0151sz\u00f6r egy tokodi csal\u00e1di h\u00e1zhoz kaptak riaszt\u00e1st, ahol a hirtelen lez\u00fadul\u00f3 csapad\u00e9kot az es\u0151csatorna nem tudta elvezetni \u00e9s befolyt a lak\u00e1sba. A tokodi \u00f6nk\u00e9ntesek az esztergomi hivat\u00e1sos t\u0171zolt\u00f3kkal egy\u00fctt szivatty\u00fak seg\u00edts\u00e9g\u00e9vel t\u00e1vol\u00edtott\u00e1k el a vizet a lak\u00e1sb\u00f3l. A tokodiak miut\u00e1n<\/p>\n","protected":false},"author":1,"featured_media":18942,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,39,6],"tags":[426,175,613,12,3559,65],"class_list":["post-18941","post","type-post","status-publish","format-standard","has-post-thumbnail","category-hirek","category-kek-hirek","category-tokod","tag-ebszonybanya","tag-katasztrofavedelem","tag-onkentesek","tag-tokod","tag-tokod-ote","tag-tuzoltosag"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>K\u00e9t esethez is riasztott\u00e1k a t\u0171zolt\u00f3kat vas\u00e1rnap d\u00e9lut\u00e1n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2019\/08\/25\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"K\u00e9t esethez is riasztott\u00e1k a t\u0171zolt\u00f3kat vas\u00e1rnap d\u00e9lut\u00e1n\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"K\u00e9t helyre is riasztott\u00e1k a tokodi \u00f6nk\u00e9nteseket, a vas\u00e1rnap d\u00e9lut\u00e1ni kedvez\u0151tlen id\u0151j\u00e1r\u00e1s okozta k\u00e1rok miatt. El\u0151sz\u00f6r egy tokodi csal\u00e1di h\u00e1zhoz kaptak riaszt\u00e1st, ahol a hirtelen lez\u00fadul\u00f3 csapad\u00e9kot az es\u0151csatorna nem tudta elvezetni \u00e9s befolyt a lak\u00e1sba. A tokodi \u00f6nk\u00e9ntesek az esztergomi hivat\u00e1sos t\u0171zolt\u00f3kkal egy\u00fctt szivatty\u00fak seg\u00edts\u00e9g\u00e9vel t\u00e1vol\u00edtott\u00e1k el a vizet a lak\u00e1sb\u00f3l. A tokodiak miut\u00e1n\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2019\/08\/25\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-25T18:42:34+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-25T18:55:07+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2019\/08\/viharkar-01.jpg?fit=670%2C365&ssl=1\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 perc\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/08\\\/25\\\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/08\\\/25\\\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"K\u00e9t esethez is riasztott\u00e1k a t\u0171zolt\u00f3kat vas\u00e1rnap d\u00e9lut\u00e1n\",\"datePublished\":\"2019-08-25T18:42:34+00:00\",\"dateModified\":\"2019-08-25T18:55:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/08\\\/25\\\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\\\/\"},\"wordCount\":198,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/08\\\/25\\\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/viharkar-01.jpg\",\"keywords\":[\"Ebsz\u0151nyb\u00e1nya\",\"katasztr\u00f3fav\u00e9delem\",\"\u00f6nk\u00e9ntesek\",\"Tokod\",\"Tokod \u00d6TE\",\"t\u0171zolt\u00f3s\u00e1g\"],\"articleSection\":[\"H\u00edrek\",\"K\u00e9k h\u00edrek\",\"Tokod\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/08\\\/25\\\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/08\\\/25\\\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\\\/\",\"name\":\"K\u00e9t esethez is riasztott\u00e1k a t\u0171zolt\u00f3kat vas\u00e1rnap d\u00e9lut\u00e1n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/08\\\/25\\\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/08\\\/25\\\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/viharkar-01.jpg\",\"datePublished\":\"2019-08-25T18:42:34+00:00\",\"dateModified\":\"2019-08-25T18:55:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/08\\\/25\\\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/08\\\/25\\\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/08\\\/25\\\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/viharkar-01.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/viharkar-01.jpg\",\"width\":670,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/08\\\/25\\\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"K\u00e9t esethez is riasztott\u00e1k a t\u0171zolt\u00f3kat vas\u00e1rnap d\u00e9lut\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"K\u00e9t esethez is riasztott\u00e1k a t\u0171zolt\u00f3kat vas\u00e1rnap d\u00e9lut\u00e1n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2019\/08\/25\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\/","og_locale":"hu_HU","og_type":"article","og_title":"K\u00e9t esethez is riasztott\u00e1k a t\u0171zolt\u00f3kat vas\u00e1rnap d\u00e9lut\u00e1n","og_description":"K\u00e9t helyre is riasztott\u00e1k a tokodi \u00f6nk\u00e9nteseket, a vas\u00e1rnap d\u00e9lut\u00e1ni kedvez\u0151tlen id\u0151j\u00e1r\u00e1s okozta k\u00e1rok miatt. El\u0151sz\u00f6r egy tokodi csal\u00e1di h\u00e1zhoz kaptak riaszt\u00e1st, ahol a hirtelen lez\u00fadul\u00f3 csapad\u00e9kot az es\u0151csatorna nem tudta elvezetni \u00e9s befolyt a lak\u00e1sba. A tokodi \u00f6nk\u00e9ntesek az esztergomi hivat\u00e1sos t\u0171zolt\u00f3kkal egy\u00fctt szivatty\u00fak seg\u00edts\u00e9g\u00e9vel t\u00e1vol\u00edtott\u00e1k el a vizet a lak\u00e1sb\u00f3l. A tokodiak miut\u00e1n","og_url":"https:\/\/dorogimedence.hu\/index.php\/2019\/08\/25\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2019-08-25T18:42:34+00:00","article_modified_time":"2019-08-25T18:55:07+00:00","og_image":[{"width":670,"height":365,"url":"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2019\/08\/viharkar-01.jpg?fit=670%2C365&ssl=1","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu","Becs\u00fclt olvas\u00e1si id\u0151":"1 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/08\/25\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/08\/25\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"K\u00e9t esethez is riasztott\u00e1k a t\u0171zolt\u00f3kat vas\u00e1rnap d\u00e9lut\u00e1n","datePublished":"2019-08-25T18:42:34+00:00","dateModified":"2019-08-25T18:55:07+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/08\/25\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\/"},"wordCount":198,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/08\/25\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2019\/08\/viharkar-01.jpg","keywords":["Ebsz\u0151nyb\u00e1nya","katasztr\u00f3fav\u00e9delem","\u00f6nk\u00e9ntesek","Tokod","Tokod \u00d6TE","t\u0171zolt\u00f3s\u00e1g"],"articleSection":["H\u00edrek","K\u00e9k h\u00edrek","Tokod"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/08\/25\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\/","url":"https:\/\/dorogimedence.hu\/index.php\/2019\/08\/25\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\/","name":"K\u00e9t esethez is riasztott\u00e1k a t\u0171zolt\u00f3kat vas\u00e1rnap d\u00e9lut\u00e1n","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/08\/25\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/08\/25\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2019\/08\/viharkar-01.jpg","datePublished":"2019-08-25T18:42:34+00:00","dateModified":"2019-08-25T18:55:07+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/08\/25\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2019\/08\/25\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/08\/25\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2019\/08\/viharkar-01.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2019\/08\/viharkar-01.jpg","width":670,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/08\/25\/ket-esethez-is-riasztottak-a-tuzoltokat-vasarnap-delutan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"K\u00e9t esethez is riasztott\u00e1k a t\u0171zolt\u00f3kat vas\u00e1rnap d\u00e9lut\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/18941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=18941"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/18941\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/18942"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=18941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=18941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=18941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}