{"id":16038,"date":"2019-04-16T19:23:09","date_gmt":"2019-04-16T17:23:09","guid":{"rendered":"http:\/\/dorogimedence.hu\/?p=16038"},"modified":"2019-04-16T19:23:09","modified_gmt":"2019-04-16T17:23:09","slug":"lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2019\/04\/16\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\/","title":{"rendered":"Lampionos V\u00edzikarnev\u00e1l Esztergom 2019 &#8211; D\u00edszits haj\u00f3t te is a Lampionosra!"},"content":{"rendered":"<p><strong>Az egyre n\u00e9pszer\u0171bb esztergomi Lampionos V\u00edzikarnev\u00e1lnak id\u00e9n te is k\u00f6nnyen a r\u00e9sztvev\u0151je lehetsz a csal\u00e1doddal, a bar\u00e1taiddal, a koll\u00e9g\u00e1kkal, vagy \u00e9ppen az iskol\u00e1s t\u00e1rsakkal, ha id\u0151ben leadod a jelentkez\u00e9sed.<\/strong><\/p>\n<p>A kreat\u00edvit\u00e1snak nem szabnak hat\u00e1rt, alkoss\u00e1tok meg ti a legsz\u00ednesebb, legfelt\u0171n\u0151bb haj\u00f3t, hiszen itt pont ez a l\u00e9nyeg!<\/p>\n<p>\u00c1prilis 28-ig v\u00e1rj\u00e1k a haj\u00f3t \u00e9p\u00edt\u0151 jelentkez\u0151ket az idei\u00a0lampionos\u00a0haj\u00f3felvonul\u00e1s szervez\u0151i.<\/p>\n<p><strong>Inf\u00f3, jelentkez\u00e9s:<\/strong>\u00a0<a href=\"mailto:novak70@gmail.com\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline; color: #0000ff;\">novak70@gmail.com<\/span><\/a>, +36305200240<\/p>\n<p><a href=\"http:\/\/fesztivalsziget.hu\/lampionos-2018\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"text-decoration: underline; color: #0000ff;\"><strong>Fot\u00f3k a tavalyi esem\u00e9nyr\u0151l&gt;&gt;<\/strong><\/span><\/a><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-16039\" src=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2019\/04\/lampionos-uj-02.jpg\" alt=\"\" width=\"670\" height=\"60\" srcset=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2019\/04\/lampionos-uj-02.jpg 670w, https:\/\/dorogimedence.hu\/wp-content\/uploads\/2019\/04\/lampionos-uj-02-300x27.jpg 300w\" sizes=\"(max-width: 670px) 100vw, 670px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Az egyre n\u00e9pszer\u0171bb esztergomi Lampionos V\u00edzikarnev\u00e1lnak id\u00e9n te is k\u00f6nnyen a r\u00e9sztvev\u0151je lehetsz a csal\u00e1doddal, a bar\u00e1taiddal, a koll\u00e9g\u00e1kkal, vagy \u00e9ppen az iskol\u00e1s t\u00e1rsakkal, ha id\u0151ben leadod a jelentkez\u00e9sed. A kreat\u00edvit\u00e1snak nem szabnak hat\u00e1rt, alkoss\u00e1tok meg ti a legsz\u00ednesebb, legfelt\u0171n\u0151bb haj\u00f3t, hiszen itt pont ez a l\u00e9nyeg! \u00c1prilis 28-ig v\u00e1rj\u00e1k a haj\u00f3t \u00e9p\u00edt\u0151 jelentkez\u0151ket az<\/p>\n","protected":false},"author":1,"featured_media":16040,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[38,3,3561],"tags":[42,2466,2410,858,101],"class_list":{"0":"post-16038","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-esztergom","8":"category-hirek","9":"category-programok","10":"tag-esztergom","11":"tag-lampionos","12":"tag-lampionos-felvonulas","13":"tag-majalis","14":"tag-program"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lampionos V\u00edzikarnev\u00e1l Esztergom 2019 - D\u00edszits haj\u00f3t te is a Lampionosra!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2019\/04\/16\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Lampionos V\u00edzikarnev\u00e1l Esztergom 2019 - D\u00edszits haj\u00f3t te is a Lampionosra!\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Az egyre n\u00e9pszer\u0171bb esztergomi Lampionos V\u00edzikarnev\u00e1lnak id\u00e9n te is k\u00f6nnyen a r\u00e9sztvev\u0151je lehetsz a csal\u00e1doddal, a bar\u00e1taiddal, a koll\u00e9g\u00e1kkal, vagy \u00e9ppen az iskol\u00e1s t\u00e1rsakkal, ha id\u0151ben leadod a jelentkez\u00e9sed. A kreat\u00edvit\u00e1snak nem szabnak hat\u00e1rt, alkoss\u00e1tok meg ti a legsz\u00ednesebb, legfelt\u0171n\u0151bb haj\u00f3t, hiszen itt pont ez a l\u00e9nyeg! \u00c1prilis 28-ig v\u00e1rj\u00e1k a haj\u00f3t \u00e9p\u00edt\u0151 jelentkez\u0151ket az\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2019\/04\/16\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-16T17:23:09+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2019\/04\/lampionos-uj-01.jpg?fit=670%2C365&ssl=1\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 perc\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/04\\\/16\\\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/04\\\/16\\\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"Lampionos V\u00edzikarnev\u00e1l Esztergom 2019 &#8211; D\u00edszits haj\u00f3t te is a Lampionosra!\",\"datePublished\":\"2019-04-16T17:23:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/04\\\/16\\\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\\\/\"},\"wordCount\":121,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/04\\\/16\\\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/lampionos-uj-01.jpg\",\"keywords\":[\"esztergom\",\"lampionos\",\"lampionos felvonul\u00e1s\",\"Maj\u00e1lis\",\"program\"],\"articleSection\":[\"Esztergom\",\"H\u00edrek\",\"Programok\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/04\\\/16\\\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/04\\\/16\\\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\\\/\",\"name\":\"Lampionos V\u00edzikarnev\u00e1l Esztergom 2019 - D\u00edszits haj\u00f3t te is a Lampionosra!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/04\\\/16\\\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/04\\\/16\\\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/lampionos-uj-01.jpg\",\"datePublished\":\"2019-04-16T17:23:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/04\\\/16\\\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/04\\\/16\\\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/04\\\/16\\\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/lampionos-uj-01.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/lampionos-uj-01.jpg\",\"width\":670,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2019\\\/04\\\/16\\\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lampionos V\u00edzikarnev\u00e1l Esztergom 2019 &#8211; D\u00edszits haj\u00f3t te is a Lampionosra!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lampionos V\u00edzikarnev\u00e1l Esztergom 2019 - D\u00edszits haj\u00f3t te is a Lampionosra!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2019\/04\/16\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\/","og_locale":"hu_HU","og_type":"article","og_title":"Lampionos V\u00edzikarnev\u00e1l Esztergom 2019 - D\u00edszits haj\u00f3t te is a Lampionosra!","og_description":"Az egyre n\u00e9pszer\u0171bb esztergomi Lampionos V\u00edzikarnev\u00e1lnak id\u00e9n te is k\u00f6nnyen a r\u00e9sztvev\u0151je lehetsz a csal\u00e1doddal, a bar\u00e1taiddal, a koll\u00e9g\u00e1kkal, vagy \u00e9ppen az iskol\u00e1s t\u00e1rsakkal, ha id\u0151ben leadod a jelentkez\u00e9sed. A kreat\u00edvit\u00e1snak nem szabnak hat\u00e1rt, alkoss\u00e1tok meg ti a legsz\u00ednesebb, legfelt\u0171n\u0151bb haj\u00f3t, hiszen itt pont ez a l\u00e9nyeg! \u00c1prilis 28-ig v\u00e1rj\u00e1k a haj\u00f3t \u00e9p\u00edt\u0151 jelentkez\u0151ket az","og_url":"https:\/\/dorogimedence.hu\/index.php\/2019\/04\/16\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2019-04-16T17:23:09+00:00","og_image":[{"width":670,"height":365,"url":"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2019\/04\/lampionos-uj-01.jpg?fit=670%2C365&ssl=1","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu","Becs\u00fclt olvas\u00e1si id\u0151":"1 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/04\/16\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/04\/16\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"Lampionos V\u00edzikarnev\u00e1l Esztergom 2019 &#8211; D\u00edszits haj\u00f3t te is a Lampionosra!","datePublished":"2019-04-16T17:23:09+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/04\/16\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\/"},"wordCount":121,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/04\/16\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2019\/04\/lampionos-uj-01.jpg","keywords":["esztergom","lampionos","lampionos felvonul\u00e1s","Maj\u00e1lis","program"],"articleSection":["Esztergom","H\u00edrek","Programok"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/04\/16\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\/","url":"https:\/\/dorogimedence.hu\/index.php\/2019\/04\/16\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\/","name":"Lampionos V\u00edzikarnev\u00e1l Esztergom 2019 - D\u00edszits haj\u00f3t te is a Lampionosra!","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/04\/16\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/04\/16\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2019\/04\/lampionos-uj-01.jpg","datePublished":"2019-04-16T17:23:09+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/04\/16\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2019\/04\/16\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/04\/16\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2019\/04\/lampionos-uj-01.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2019\/04\/lampionos-uj-01.jpg","width":670,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2019\/04\/16\/lampionos-vizikarneval-esztergom-2019-diszits-hajot-te-is-a-lampionosra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"Lampionos V\u00edzikarnev\u00e1l Esztergom 2019 &#8211; D\u00edszits haj\u00f3t te is a Lampionosra!"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/16038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=16038"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/16038\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/16040"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=16038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=16038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=16038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}