{"id":1394,"date":"2017-03-11T09:31:11","date_gmt":"2017-03-11T08:31:11","guid":{"rendered":"http:\/\/dorogimedence.hu\/?p=1394"},"modified":"2017-03-11T09:31:11","modified_gmt":"2017-03-11T08:31:11","slug":"megemlekezes-taton","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2017\/03\/11\/megemlekezes-taton\/","title":{"rendered":"Megeml\u00e9kez\u00e9s T\u00e1ton"},"content":{"rendered":"<p>A II. vil\u00e1gh\u00e1bor\u00fa 72. \u00e9vfordul\u00f3ja alkalm\u00e1b\u00f3l megeml\u00e9kez\u00e9st tartanak m\u00e1rcius 26-\u00e1n, vas\u00e1rnap 11 \u00f3r\u00e1t\u00f3l T\u00e1ton a II. vil\u00e1gh\u00e1bor\u00fas eml\u00e9km\u0171n\u00e9l.<\/p>\n<p>Az esem\u00e9nyen besz\u00e9det mond H\u00e1mos L\u00e1szl\u00f3 a T\u00e1ti Kult\u00farh\u00e1z igazgat\u00f3ja.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large wp-image-1395\" src=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/03\/megemlekezes-tat-724x1024.jpg\" alt=\"\" width=\"665\" height=\"941\" srcset=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/03\/megemlekezes-tat-724x1024.jpg 724w, https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/03\/megemlekezes-tat-212x300.jpg 212w, https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/03\/megemlekezes-tat-768x1086.jpg 768w\" sizes=\"(max-width: 665px) 100vw, 665px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A II. vil\u00e1gh\u00e1bor\u00fa 72. \u00e9vfordul\u00f3ja alkalm\u00e1b\u00f3l megeml\u00e9kez\u00e9st tartanak m\u00e1rcius 26-\u00e1n, vas\u00e1rnap 11 \u00f3r\u00e1t\u00f3l T\u00e1ton a II. vil\u00e1gh\u00e1bor\u00fas eml\u00e9km\u0171n\u00e9l. Az esem\u00e9nyen besz\u00e9det mond H\u00e1mos L\u00e1szl\u00f3 a T\u00e1ti Kult\u00farh\u00e1z igazgat\u00f3ja.<\/p>\n","protected":false},"author":1,"featured_media":1396,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,110],"tags":[477,192,111],"class_list":{"0":"post-1394","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-hirek","8":"category-tat","9":"tag-ii-vilaghaboru","10":"tag-megemlekezes","11":"tag-tat"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Megeml\u00e9kez\u00e9s T\u00e1ton<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2017\/03\/11\/megemlekezes-taton\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Megeml\u00e9kez\u00e9s T\u00e1ton\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"A II. vil\u00e1gh\u00e1bor\u00fa 72. \u00e9vfordul\u00f3ja alkalm\u00e1b\u00f3l megeml\u00e9kez\u00e9st tartanak m\u00e1rcius 26-\u00e1n, vas\u00e1rnap 11 \u00f3r\u00e1t\u00f3l T\u00e1ton a II. vil\u00e1gh\u00e1bor\u00fas eml\u00e9km\u0171n\u00e9l. Az esem\u00e9nyen besz\u00e9det mond H\u00e1mos L\u00e1szl\u00f3 a T\u00e1ti Kult\u00farh\u00e1z igazgat\u00f3ja.\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2017\/03\/11\/megemlekezes-taton\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2017-03-11T08:31:11+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/03\/masodik-vh.jpg?fit=1024%2C681&ssl=1\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"681\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/03\\\/11\\\/megemlekezes-taton\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/03\\\/11\\\/megemlekezes-taton\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"Megeml\u00e9kez\u00e9s T\u00e1ton\",\"datePublished\":\"2017-03-11T08:31:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/03\\\/11\\\/megemlekezes-taton\\\/\"},\"wordCount\":58,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/03\\\/11\\\/megemlekezes-taton\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/masodik-vh.jpg\",\"keywords\":[\"II. vil\u00e1gh\u00e1bor\u00fa\",\"megeml\u00e9kez\u00e9s\",\"T\u00e1t\"],\"articleSection\":[\"H\u00edrek\",\"T\u00e1t\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/03\\\/11\\\/megemlekezes-taton\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/03\\\/11\\\/megemlekezes-taton\\\/\",\"name\":\"Megeml\u00e9kez\u00e9s T\u00e1ton\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/03\\\/11\\\/megemlekezes-taton\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/03\\\/11\\\/megemlekezes-taton\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/masodik-vh.jpg\",\"datePublished\":\"2017-03-11T08:31:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/03\\\/11\\\/megemlekezes-taton\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/03\\\/11\\\/megemlekezes-taton\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/03\\\/11\\\/megemlekezes-taton\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/masodik-vh.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/masodik-vh.jpg\",\"width\":1024,\"height\":681},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2017\\\/03\\\/11\\\/megemlekezes-taton\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Megeml\u00e9kez\u00e9s T\u00e1ton\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Megeml\u00e9kez\u00e9s T\u00e1ton","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2017\/03\/11\/megemlekezes-taton\/","og_locale":"hu_HU","og_type":"article","og_title":"Megeml\u00e9kez\u00e9s T\u00e1ton","og_description":"A II. vil\u00e1gh\u00e1bor\u00fa 72. \u00e9vfordul\u00f3ja alkalm\u00e1b\u00f3l megeml\u00e9kez\u00e9st tartanak m\u00e1rcius 26-\u00e1n, vas\u00e1rnap 11 \u00f3r\u00e1t\u00f3l T\u00e1ton a II. vil\u00e1gh\u00e1bor\u00fas eml\u00e9km\u0171n\u00e9l. Az esem\u00e9nyen besz\u00e9det mond H\u00e1mos L\u00e1szl\u00f3 a T\u00e1ti Kult\u00farh\u00e1z igazgat\u00f3ja.","og_url":"https:\/\/dorogimedence.hu\/index.php\/2017\/03\/11\/megemlekezes-taton\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2017-03-11T08:31:11+00:00","og_image":[{"width":1024,"height":681,"url":"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2017\/03\/masodik-vh.jpg?fit=1024%2C681&ssl=1","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/03\/11\/megemlekezes-taton\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/03\/11\/megemlekezes-taton\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"Megeml\u00e9kez\u00e9s T\u00e1ton","datePublished":"2017-03-11T08:31:11+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/03\/11\/megemlekezes-taton\/"},"wordCount":58,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/03\/11\/megemlekezes-taton\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/03\/masodik-vh.jpg","keywords":["II. vil\u00e1gh\u00e1bor\u00fa","megeml\u00e9kez\u00e9s","T\u00e1t"],"articleSection":["H\u00edrek","T\u00e1t"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/03\/11\/megemlekezes-taton\/","url":"https:\/\/dorogimedence.hu\/index.php\/2017\/03\/11\/megemlekezes-taton\/","name":"Megeml\u00e9kez\u00e9s T\u00e1ton","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/03\/11\/megemlekezes-taton\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/03\/11\/megemlekezes-taton\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/03\/masodik-vh.jpg","datePublished":"2017-03-11T08:31:11+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/03\/11\/megemlekezes-taton\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2017\/03\/11\/megemlekezes-taton\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/03\/11\/megemlekezes-taton\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/03\/masodik-vh.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2017\/03\/masodik-vh.jpg","width":1024,"height":681},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2017\/03\/11\/megemlekezes-taton\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"Megeml\u00e9kez\u00e9s T\u00e1ton"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/1394","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=1394"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/1394\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/1396"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=1394"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=1394"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=1394"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}