{"id":13129,"date":"2018-11-06T13:41:57","date_gmt":"2018-11-06T12:41:57","guid":{"rendered":"http:\/\/dorogimedence.hu\/?p=13129"},"modified":"2018-11-06T13:41:57","modified_gmt":"2018-11-06T12:41:57","slug":"osztondij-program-dorogi-diakoknak-is","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2018\/11\/06\/osztondij-program-dorogi-diakoknak-is\/","title":{"rendered":"\u00d6szt\u00f6nd\u00edj-program dorogi di\u00e1koknak is!"},"content":{"rendered":"<p><strong>A Trendhim Scolarship \u00f6szt\u00f6nd\u00edj-programot di\u00e1koknak hozt\u00e1k l\u00e9tre, hogy t\u00e1mogass\u00e1k \u00e9s er\u0151s\u00edts\u00e9k az e-kereskedelmi szuperszt\u00e1rok j\u00f6v\u0151j\u00e9t.<\/strong><\/p>\n<p>Arr\u00f3l \u00e1lmodozol, hogy marketing, divat, IT, kereskedelem, menedzsment vagy sales ter\u00fcleten helyezkedsz el? Ha igen, akkor sz\u00edvesen seg\u00edtenek neked. A d\u00e1niai sz\u00e9khely\u0171 sz\u00e9ps\u00e9g\u00e1pol\u00e1si term\u00e9kek kereskedelm\u00e9vel foglalkoz\u00f3 Trendhim ApS minden \u00e9vben t\u00e1mogat egy vagy t\u00f6bb hallgat\u00f3t 2.000 eur\u00f3val. A nyertes di\u00e1k a 2.000 eur\u00f3s nyerem\u00e9nyt az utaz\u00e1st\u00f3l kezdve eg\u00e9szen tanulm\u00e1nyok finansz\u00edroz\u00e1s\u00e1ig b\u00e1rmire felhaszn\u00e1lhatja.<\/p>\n<p>P\u00e1ly\u00e1zni eredetileg 2018. november 1-j\u00e9ig lehetett, viszont a jelentkez\u00e9si hat\u00e1rid\u0151t tov\u00e1bbi h\u00e1rom h\u00e9ttel meghosszabb\u00edtott\u00e1k \u2013 mondta el Rad\u00e1nyi Lili, a v\u00e1llalat marketing managere.<\/p>\n<p><a href=\"https:\/\/www.trendhim.hu\/csr\/trendhim-scholarship\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline; color: #0000ff;\"><strong>R\u00e9szletek a p\u00e1ly\u00e1zattal kapcsolatban&gt;&gt;<\/strong><\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Trendhim Scolarship \u00f6szt\u00f6nd\u00edj-programot di\u00e1koknak hozt\u00e1k l\u00e9tre, hogy t\u00e1mogass\u00e1k \u00e9s er\u0151s\u00edts\u00e9k az e-kereskedelmi szuperszt\u00e1rok j\u00f6v\u0151j\u00e9t. Arr\u00f3l \u00e1lmodozol, hogy marketing, divat, IT, kereskedelem, menedzsment vagy sales ter\u00fcleten helyezkedsz el? Ha igen, akkor sz\u00edvesen seg\u00edtenek neked. A d\u00e1niai sz\u00e9khely\u0171 sz\u00e9ps\u00e9g\u00e1pol\u00e1si term\u00e9kek kereskedelm\u00e9vel foglalkoz\u00f3 Trendhim ApS minden \u00e9vben t\u00e1mogat egy vagy t\u00f6bb hallgat\u00f3t 2.000 eur\u00f3val. A nyertes di\u00e1k<\/p>\n","protected":false},"author":1,"featured_media":13130,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[2,3],"tags":[15,142,143,74,101,3177],"class_list":{"0":"post-13129","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-dorog","8":"category-hirek","9":"tag-dorog","10":"tag-oktatas","11":"tag-osztondij","12":"tag-palyazat","13":"tag-program","14":"tag-trendhim"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00d6szt\u00f6nd\u00edj-program dorogi di\u00e1koknak is!<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2018\/11\/06\/osztondij-program-dorogi-diakoknak-is\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"\u00d6szt\u00f6nd\u00edj-program dorogi di\u00e1koknak is!\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"A Trendhim Scolarship \u00f6szt\u00f6nd\u00edj-programot di\u00e1koknak hozt\u00e1k l\u00e9tre, hogy t\u00e1mogass\u00e1k \u00e9s er\u0151s\u00edts\u00e9k az e-kereskedelmi szuperszt\u00e1rok j\u00f6v\u0151j\u00e9t. Arr\u00f3l \u00e1lmodozol, hogy marketing, divat, IT, kereskedelem, menedzsment vagy sales ter\u00fcleten helyezkedsz el? Ha igen, akkor sz\u00edvesen seg\u00edtenek neked. A d\u00e1niai sz\u00e9khely\u0171 sz\u00e9ps\u00e9g\u00e1pol\u00e1si term\u00e9kek kereskedelm\u00e9vel foglalkoz\u00f3 Trendhim ApS minden \u00e9vben t\u00e1mogat egy vagy t\u00f6bb hallgat\u00f3t 2.000 eur\u00f3val. A nyertes di\u00e1k\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2018\/11\/06\/osztondij-program-dorogi-diakoknak-is\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-06T12:41:57+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2018\/11\/osztondij.jpg?fit=670%2C365&ssl=1\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 perc\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/11\\\/06\\\/osztondij-program-dorogi-diakoknak-is\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/11\\\/06\\\/osztondij-program-dorogi-diakoknak-is\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"\u00d6szt\u00f6nd\u00edj-program dorogi di\u00e1koknak is!\",\"datePublished\":\"2018-11-06T12:41:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/11\\\/06\\\/osztondij-program-dorogi-diakoknak-is\\\/\"},\"wordCount\":157,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/11\\\/06\\\/osztondij-program-dorogi-diakoknak-is\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/osztondij.jpg\",\"keywords\":[\"Dorog\",\"oktat\u00e1s\",\"\u00f6szt\u00f6nd\u00edj\",\"p\u00e1ly\u00e1zat\",\"program\",\"Trendhim\"],\"articleSection\":[\"Dorog\",\"H\u00edrek\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/11\\\/06\\\/osztondij-program-dorogi-diakoknak-is\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/11\\\/06\\\/osztondij-program-dorogi-diakoknak-is\\\/\",\"name\":\"\u00d6szt\u00f6nd\u00edj-program dorogi di\u00e1koknak is!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/11\\\/06\\\/osztondij-program-dorogi-diakoknak-is\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/11\\\/06\\\/osztondij-program-dorogi-diakoknak-is\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/osztondij.jpg\",\"datePublished\":\"2018-11-06T12:41:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/11\\\/06\\\/osztondij-program-dorogi-diakoknak-is\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/11\\\/06\\\/osztondij-program-dorogi-diakoknak-is\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/11\\\/06\\\/osztondij-program-dorogi-diakoknak-is\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/osztondij.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/osztondij.jpg\",\"width\":670,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/11\\\/06\\\/osztondij-program-dorogi-diakoknak-is\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00d6szt\u00f6nd\u00edj-program dorogi di\u00e1koknak is!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00d6szt\u00f6nd\u00edj-program dorogi di\u00e1koknak is!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2018\/11\/06\/osztondij-program-dorogi-diakoknak-is\/","og_locale":"hu_HU","og_type":"article","og_title":"\u00d6szt\u00f6nd\u00edj-program dorogi di\u00e1koknak is!","og_description":"A Trendhim Scolarship \u00f6szt\u00f6nd\u00edj-programot di\u00e1koknak hozt\u00e1k l\u00e9tre, hogy t\u00e1mogass\u00e1k \u00e9s er\u0151s\u00edts\u00e9k az e-kereskedelmi szuperszt\u00e1rok j\u00f6v\u0151j\u00e9t. Arr\u00f3l \u00e1lmodozol, hogy marketing, divat, IT, kereskedelem, menedzsment vagy sales ter\u00fcleten helyezkedsz el? Ha igen, akkor sz\u00edvesen seg\u00edtenek neked. A d\u00e1niai sz\u00e9khely\u0171 sz\u00e9ps\u00e9g\u00e1pol\u00e1si term\u00e9kek kereskedelm\u00e9vel foglalkoz\u00f3 Trendhim ApS minden \u00e9vben t\u00e1mogat egy vagy t\u00f6bb hallgat\u00f3t 2.000 eur\u00f3val. A nyertes di\u00e1k","og_url":"https:\/\/dorogimedence.hu\/index.php\/2018\/11\/06\/osztondij-program-dorogi-diakoknak-is\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2018-11-06T12:41:57+00:00","og_image":[{"width":670,"height":365,"url":"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2018\/11\/osztondij.jpg?fit=670%2C365&ssl=1","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu","Becs\u00fclt olvas\u00e1si id\u0151":"1 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/11\/06\/osztondij-program-dorogi-diakoknak-is\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/11\/06\/osztondij-program-dorogi-diakoknak-is\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"\u00d6szt\u00f6nd\u00edj-program dorogi di\u00e1koknak is!","datePublished":"2018-11-06T12:41:57+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/11\/06\/osztondij-program-dorogi-diakoknak-is\/"},"wordCount":157,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/11\/06\/osztondij-program-dorogi-diakoknak-is\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/11\/osztondij.jpg","keywords":["Dorog","oktat\u00e1s","\u00f6szt\u00f6nd\u00edj","p\u00e1ly\u00e1zat","program","Trendhim"],"articleSection":["Dorog","H\u00edrek"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/11\/06\/osztondij-program-dorogi-diakoknak-is\/","url":"https:\/\/dorogimedence.hu\/index.php\/2018\/11\/06\/osztondij-program-dorogi-diakoknak-is\/","name":"\u00d6szt\u00f6nd\u00edj-program dorogi di\u00e1koknak is!","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/11\/06\/osztondij-program-dorogi-diakoknak-is\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/11\/06\/osztondij-program-dorogi-diakoknak-is\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/11\/osztondij.jpg","datePublished":"2018-11-06T12:41:57+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/11\/06\/osztondij-program-dorogi-diakoknak-is\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2018\/11\/06\/osztondij-program-dorogi-diakoknak-is\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/11\/06\/osztondij-program-dorogi-diakoknak-is\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/11\/osztondij.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/11\/osztondij.jpg","width":670,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/11\/06\/osztondij-program-dorogi-diakoknak-is\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"\u00d6szt\u00f6nd\u00edj-program dorogi di\u00e1koknak is!"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/13129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=13129"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/13129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/13130"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=13129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=13129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=13129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}