{"id":12415,"date":"2018-09-21T16:29:41","date_gmt":"2018-09-21T14:29:41","guid":{"rendered":"http:\/\/dorogimedence.hu\/?p=12415"},"modified":"2018-09-21T16:29:41","modified_gmt":"2018-09-21T14:29:41","slug":"szureti-nap-kesztolcon","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2018\/09\/21\/szureti-nap-kesztolcon\/","title":{"rendered":"Sz\u00fcreti nap Keszt\u00f6lc\u00f6n"},"content":{"rendered":"<p><strong>Szeptember 22-\u00e9n, szombaton sz\u00fcreti napot tartanak Keszt\u00f6lc\u00f6n, a M\u0171vel\u0151d\u00e9si H\u00e1zban.<\/strong><\/p>\n<p>A sz\u00fcreti felvonul\u00e1s 15 \u00f3rakor indul a Szent Kelemen t\u00e9rr\u0151l, 16 \u00f3r\u00e1t\u00f3l pedig a keszt\u00f6lci \u00f3vod\u00e1sok m\u0171sora tekinhet\u0151 meg. Fell\u00e9p a Pilisi Kolibri STE, a keszt\u00f6lci zumb\u00e1sok \u00e9s a keszt\u00f6lci ovis t\u00e1nccsoport Salik Kata vezet\u00e9s\u00e9vel. De a Piliscs\u00e9vi Trnka n\u00e9pt\u00e1nccsoport \u00e9s a keszt\u00f6lci P\u00e1vak\u00f6r m\u0171sor\u00e1t is \u00e9lvezhetik az \u00e9rdekl\u0151d\u0151k. Mindemellett Geiszler D\u00f3ra harm\u00f3nik\u00e1val, Szab\u00f3 Kata pedig \u00e9nekkel sz\u00ednes\u00edti az esem\u00e9nyt. 17 \u00f3r\u00e1t\u00f3l pedig Egri J\u00f3zsef operett m\u0171sora hallgathat\u00f3 meg.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-12416\" src=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/09\/megh\u00edv\u00f3-sz\u00fcreti-nap-2018-Keszt\u00f6lc-page-001.jpg.600x0_q85.jpg\" alt=\"\" width=\"600\" height=\"849\" srcset=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/09\/megh\u00edv\u00f3-sz\u00fcreti-nap-2018-Keszt\u00f6lc-page-001.jpg.600x0_q85.jpg 600w, https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/09\/megh\u00edv\u00f3-sz\u00fcreti-nap-2018-Keszt\u00f6lc-page-001.jpg.600x0_q85-212x300.jpg 212w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Szeptember 22-\u00e9n, szombaton sz\u00fcreti napot tartanak Keszt\u00f6lc\u00f6n, a M\u0171vel\u0151d\u00e9si H\u00e1zban. A sz\u00fcreti felvonul\u00e1s 15 \u00f3rakor indul a Szent Kelemen t\u00e9rr\u0151l, 16 \u00f3r\u00e1t\u00f3l pedig a keszt\u00f6lci \u00f3vod\u00e1sok m\u0171sora tekinhet\u0151 meg. Fell\u00e9p a Pilisi Kolibri STE, a keszt\u00f6lci zumb\u00e1sok \u00e9s a keszt\u00f6lci ovis t\u00e1nccsoport Salik Kata vezet\u00e9s\u00e9vel. De a Piliscs\u00e9vi Trnka n\u00e9pt\u00e1nccsoport \u00e9s a keszt\u00f6lci P\u00e1vak\u00f6r m\u0171sor\u00e1t<\/p>\n","protected":false},"author":1,"featured_media":12417,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,8],"tags":[129,1421,1610,3034],"class_list":{"0":"post-12415","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-hirek","8":"category-kesztolc","9":"tag-kesztolc","10":"tag-szuret","11":"tag-szureti-felvonulas","12":"tag-szureti-nap"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sz\u00fcreti nap Keszt\u00f6lc\u00f6n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2018\/09\/21\/szureti-nap-kesztolcon\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Sz\u00fcreti nap Keszt\u00f6lc\u00f6n\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Szeptember 22-\u00e9n, szombaton sz\u00fcreti napot tartanak Keszt\u00f6lc\u00f6n, a M\u0171vel\u0151d\u00e9si H\u00e1zban. A sz\u00fcreti felvonul\u00e1s 15 \u00f3rakor indul a Szent Kelemen t\u00e9rr\u0151l, 16 \u00f3r\u00e1t\u00f3l pedig a keszt\u00f6lci \u00f3vod\u00e1sok m\u0171sora tekinhet\u0151 meg. Fell\u00e9p a Pilisi Kolibri STE, a keszt\u00f6lci zumb\u00e1sok \u00e9s a keszt\u00f6lci ovis t\u00e1nccsoport Salik Kata vezet\u00e9s\u00e9vel. De a Piliscs\u00e9vi Trnka n\u00e9pt\u00e1nccsoport \u00e9s a keszt\u00f6lci P\u00e1vak\u00f6r m\u0171sor\u00e1t\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2018\/09\/21\/szureti-nap-kesztolcon\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-21T14:29:41+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2018\/09\/szuret-02.jpg?fit=670%2C365&ssl=1\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:label2\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 perc\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/09\\\/21\\\/szureti-nap-kesztolcon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/09\\\/21\\\/szureti-nap-kesztolcon\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"Sz\u00fcreti nap Keszt\u00f6lc\u00f6n\",\"datePublished\":\"2018-09-21T14:29:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/09\\\/21\\\/szureti-nap-kesztolcon\\\/\"},\"wordCount\":126,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/09\\\/21\\\/szureti-nap-kesztolcon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/szuret-02.jpg\",\"keywords\":[\"Keszt\u00f6lc\",\"sz\u00fcret\",\"Sz\u00fcreti felvonul\u00e1s\",\"sz\u00fcreti nap\"],\"articleSection\":[\"H\u00edrek\",\"Keszt\u00f6lc\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/09\\\/21\\\/szureti-nap-kesztolcon\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/09\\\/21\\\/szureti-nap-kesztolcon\\\/\",\"name\":\"Sz\u00fcreti nap Keszt\u00f6lc\u00f6n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/09\\\/21\\\/szureti-nap-kesztolcon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/09\\\/21\\\/szureti-nap-kesztolcon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/szuret-02.jpg\",\"datePublished\":\"2018-09-21T14:29:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/09\\\/21\\\/szureti-nap-kesztolcon\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/09\\\/21\\\/szureti-nap-kesztolcon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/09\\\/21\\\/szureti-nap-kesztolcon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/szuret-02.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/szuret-02.jpg\",\"width\":670,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/09\\\/21\\\/szureti-nap-kesztolcon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sz\u00fcreti nap Keszt\u00f6lc\u00f6n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sz\u00fcreti nap Keszt\u00f6lc\u00f6n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2018\/09\/21\/szureti-nap-kesztolcon\/","og_locale":"hu_HU","og_type":"article","og_title":"Sz\u00fcreti nap Keszt\u00f6lc\u00f6n","og_description":"Szeptember 22-\u00e9n, szombaton sz\u00fcreti napot tartanak Keszt\u00f6lc\u00f6n, a M\u0171vel\u0151d\u00e9si H\u00e1zban. A sz\u00fcreti felvonul\u00e1s 15 \u00f3rakor indul a Szent Kelemen t\u00e9rr\u0151l, 16 \u00f3r\u00e1t\u00f3l pedig a keszt\u00f6lci \u00f3vod\u00e1sok m\u0171sora tekinhet\u0151 meg. Fell\u00e9p a Pilisi Kolibri STE, a keszt\u00f6lci zumb\u00e1sok \u00e9s a keszt\u00f6lci ovis t\u00e1nccsoport Salik Kata vezet\u00e9s\u00e9vel. De a Piliscs\u00e9vi Trnka n\u00e9pt\u00e1nccsoport \u00e9s a keszt\u00f6lci P\u00e1vak\u00f6r m\u0171sor\u00e1t","og_url":"https:\/\/dorogimedence.hu\/index.php\/2018\/09\/21\/szureti-nap-kesztolcon\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2018-09-21T14:29:41+00:00","og_image":[{"width":670,"height":365,"url":"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2018\/09\/szuret-02.jpg?fit=670%2C365&ssl=1","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu","Becs\u00fclt olvas\u00e1si id\u0151":"1 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/09\/21\/szureti-nap-kesztolcon\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/09\/21\/szureti-nap-kesztolcon\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"Sz\u00fcreti nap Keszt\u00f6lc\u00f6n","datePublished":"2018-09-21T14:29:41+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/09\/21\/szureti-nap-kesztolcon\/"},"wordCount":126,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/09\/21\/szureti-nap-kesztolcon\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/09\/szuret-02.jpg","keywords":["Keszt\u00f6lc","sz\u00fcret","Sz\u00fcreti felvonul\u00e1s","sz\u00fcreti nap"],"articleSection":["H\u00edrek","Keszt\u00f6lc"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/09\/21\/szureti-nap-kesztolcon\/","url":"https:\/\/dorogimedence.hu\/index.php\/2018\/09\/21\/szureti-nap-kesztolcon\/","name":"Sz\u00fcreti nap Keszt\u00f6lc\u00f6n","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/09\/21\/szureti-nap-kesztolcon\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/09\/21\/szureti-nap-kesztolcon\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/09\/szuret-02.jpg","datePublished":"2018-09-21T14:29:41+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/09\/21\/szureti-nap-kesztolcon\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2018\/09\/21\/szureti-nap-kesztolcon\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/09\/21\/szureti-nap-kesztolcon\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/09\/szuret-02.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/09\/szuret-02.jpg","width":670,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/09\/21\/szureti-nap-kesztolcon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"Sz\u00fcreti nap Keszt\u00f6lc\u00f6n"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/12415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=12415"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/12415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/12417"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=12415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=12415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=12415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}