{"id":10863,"date":"2018-06-25T17:04:19","date_gmt":"2018-06-25T15:04:19","guid":{"rendered":"http:\/\/dorogimedence.hu\/?p=10863"},"modified":"2018-06-25T17:04:19","modified_gmt":"2018-06-25T15:04:19","slug":"iden-is-var-a-tokodi-borut","status":"publish","type":"post","link":"https:\/\/dorogimedence.hu\/index.php\/2018\/06\/25\/iden-is-var-a-tokodi-borut\/","title":{"rendered":"Id\u00e9n is v\u00e1r a Tokodi Bor\u00fat"},"content":{"rendered":"<p><strong>Id\u00e9n mutatkozik be a Bortours Programiroda a Tokodi Bor\u00fat szervez\u00e9s\u00e9ben. Most szombaton, vagyis j\u00fanius 30-\u00e1n ism\u00e9t 12 pinc\u00e9n\u00e9l k\u00f3stolhatnak a r\u00e9sztvev\u0151k.<\/strong><\/p>\n<p>Emellett persze p\u00e1link\u00e1t is lesz lehet\u0151s\u00e9g \u00edzlelni. A Nagyv\u00f6lgyben b\u00fcf\u00e9 \u00e9s italb\u00e1r is m\u0171k\u00f6dik majd. Sz\u00ednpadon a t\u00f6retlen sikernek \u00f6rvend\u0151 P\u00e1 Di-Di t\u00e1ncegy\u00fcttes, Mr\u00e1z Anita \u00e9s Wolf Kati. Ezt k\u00f6vet\u0151en video disco \u00e9s t\u00e1nc kifullad\u00e1sig. \u201cDer\u0171re Bor\u00fat!\u201d<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/events\/214846029014556\/\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline; color: #0000ff;\"><strong>Facebook esem\u00e9ny&gt;&gt;<\/strong><\/span><\/a><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-large wp-image-10865\" src=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/06\/tokodi-borut-02-548x1024.jpg\" alt=\"\" width=\"548\" height=\"1024\" srcset=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/06\/tokodi-borut-02-548x1024.jpg 548w, https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/06\/tokodi-borut-02-161x300.jpg 161w, https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/06\/tokodi-borut-02.jpg 594w\" sizes=\"(max-width: 548px) 100vw, 548px\" \/><\/p>\n<p><img decoding=\"async\" class=\"alignnone size-large wp-image-10866\" src=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/06\/tokodi-borut-03-548x1024.jpg\" alt=\"\" width=\"548\" height=\"1024\" srcset=\"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/06\/tokodi-borut-03-548x1024.jpg 548w, https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/06\/tokodi-borut-03-161x300.jpg 161w, https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/06\/tokodi-borut-03.jpg 594w\" sizes=\"(max-width: 548px) 100vw, 548px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Id\u00e9n mutatkozik be a Bortours Programiroda a Tokodi Bor\u00fat szervez\u00e9s\u00e9ben. Most szombaton, vagyis j\u00fanius 30-\u00e1n ism\u00e9t 12 pinc\u00e9n\u00e9l k\u00f3stolhatnak a r\u00e9sztvev\u0151k. Emellett persze p\u00e1link\u00e1t is lesz lehet\u0151s\u00e9g \u00edzlelni. A Nagyv\u00f6lgyben b\u00fcf\u00e9 \u00e9s italb\u00e1r is m\u0171k\u00f6dik majd. Sz\u00ednpadon a t\u00f6retlen sikernek \u00f6rvend\u0151 P\u00e1 Di-Di t\u00e1ncegy\u00fcttes, Mr\u00e1z Anita \u00e9s Wolf Kati. Ezt k\u00f6vet\u0151en video disco \u00e9s t\u00e1nc<\/p>\n","protected":false},"author":1,"featured_media":10864,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,6],"tags":[610,660,119,717,12,1200],"class_list":{"0":"post-10863","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-hirek","8":"category-tokod","9":"tag-borfesztival","10":"tag-fesztival","11":"tag-koncert","12":"tag-szorakozas","13":"tag-tokod","14":"tag-tokodi-borut"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Id\u00e9n is v\u00e1r a Tokodi Bor\u00fat<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dorogimedence.hu\/index.php\/2018\/06\/25\/iden-is-var-a-tokodi-borut\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:type\" content=\"article\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:title\" content=\"Id\u00e9n is v\u00e1r a Tokodi Bor\u00fat\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:description\" content=\"Id\u00e9n mutatkozik be a Bortours Programiroda a Tokodi Bor\u00fat szervez\u00e9s\u00e9ben. Most szombaton, vagyis j\u00fanius 30-\u00e1n ism\u00e9t 12 pinc\u00e9n\u00e9l k\u00f3stolhatnak a r\u00e9sztvev\u0151k. Emellett persze p\u00e1link\u00e1t is lesz lehet\u0151s\u00e9g \u00edzlelni. A Nagyv\u00f6lgyben b\u00fcf\u00e9 \u00e9s italb\u00e1r is m\u0171k\u00f6dik majd. Sz\u00ednpadon a t\u00f6retlen sikernek \u00f6rvend\u0151 P\u00e1 Di-Di t\u00e1ncegy\u00fcttes, Mr\u00e1z Anita \u00e9s Wolf Kati. Ezt k\u00f6vet\u0151en video disco \u00e9s t\u00e1nc\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dorogimedence.hu\/index.php\/2018\/06\/25\/iden-is-var-a-tokodi-borut\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:site_name\" content=\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dorogimedence\/\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-25T15:04:19+00:00\" class=\"yoast-seo-meta-tag\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2018\/06\/tokodi-borut-01.jpg?fit=670%2C365&ssl=1\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:height\" content=\"365\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"author\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" class=\"yoast-seo-meta-tag\" \/>\n<meta name=\"twitter:label1\" content=\"Szerz\u0151:\" class=\"yoast-seo-meta-tag\" \/>\n\t<meta name=\"twitter:data1\" content=\"dorogimedence.hu\" class=\"yoast-seo-meta-tag\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/06\\\/25\\\/iden-is-var-a-tokodi-borut\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/06\\\/25\\\/iden-is-var-a-tokodi-borut\\\/\"},\"author\":{\"name\":\"dorogimedence.hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\"},\"headline\":\"Id\u00e9n is v\u00e1r a Tokodi Bor\u00fat\",\"datePublished\":\"2018-06-25T15:04:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/06\\\/25\\\/iden-is-var-a-tokodi-borut\\\/\"},\"wordCount\":103,\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/06\\\/25\\\/iden-is-var-a-tokodi-borut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/tokodi-borut-01.jpg\",\"keywords\":[\"borfesztiv\u00e1l\",\"fesztiv\u00e1l\",\"koncert\",\"sz\u00f3rakoz\u00e1s\",\"Tokod\",\"Tokodi Bor\u00fat\"],\"articleSection\":[\"H\u00edrek\",\"Tokod\"],\"inLanguage\":\"hu\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/06\\\/25\\\/iden-is-var-a-tokodi-borut\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/06\\\/25\\\/iden-is-var-a-tokodi-borut\\\/\",\"name\":\"Id\u00e9n is v\u00e1r a Tokodi Bor\u00fat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/06\\\/25\\\/iden-is-var-a-tokodi-borut\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/06\\\/25\\\/iden-is-var-a-tokodi-borut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/tokodi-borut-01.jpg\",\"datePublished\":\"2018-06-25T15:04:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/06\\\/25\\\/iden-is-var-a-tokodi-borut\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/06\\\/25\\\/iden-is-var-a-tokodi-borut\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/06\\\/25\\\/iden-is-var-a-tokodi-borut\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/tokodi-borut-01.jpg\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2018\\\/06\\\/tokodi-borut-01.jpg\",\"width\":670,\"height\":365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/index.php\\\/2018\\\/06\\\/25\\\/iden-is-var-a-tokodi-borut\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/dorogimedence.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Id\u00e9n is v\u00e1r a Tokodi Bor\u00fat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#website\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"description\":\"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok\",\"publisher\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dorogimedence.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#organization\",\"name\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"contentUrl\":\"https:\\\/\\\/dorogimedence.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/logo-feher-600.png\",\"width\":600,\"height\":100,\"caption\":\"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l\"},\"image\":{\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dorogimedence\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dorogimedence.hu\\\/#\\\/schema\\\/person\\\/ce6091eeb7e95ecdc87890d6aa8e0fd4\",\"name\":\"dorogimedence.hu\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"url\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"contentUrl\":\"\\\/\\\/www.gravatar.com\\\/avatar\\\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm\",\"caption\":\"dorogimedence.hu\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Id\u00e9n is v\u00e1r a Tokodi Bor\u00fat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dorogimedence.hu\/index.php\/2018\/06\/25\/iden-is-var-a-tokodi-borut\/","og_locale":"hu_HU","og_type":"article","og_title":"Id\u00e9n is v\u00e1r a Tokodi Bor\u00fat","og_description":"Id\u00e9n mutatkozik be a Bortours Programiroda a Tokodi Bor\u00fat szervez\u00e9s\u00e9ben. Most szombaton, vagyis j\u00fanius 30-\u00e1n ism\u00e9t 12 pinc\u00e9n\u00e9l k\u00f3stolhatnak a r\u00e9sztvev\u0151k. Emellett persze p\u00e1link\u00e1t is lesz lehet\u0151s\u00e9g \u00edzlelni. A Nagyv\u00f6lgyben b\u00fcf\u00e9 \u00e9s italb\u00e1r is m\u0171k\u00f6dik majd. Sz\u00ednpadon a t\u00f6retlen sikernek \u00f6rvend\u0151 P\u00e1 Di-Di t\u00e1ncegy\u00fcttes, Mr\u00e1z Anita \u00e9s Wolf Kati. Ezt k\u00f6vet\u0151en video disco \u00e9s t\u00e1nc","og_url":"https:\/\/dorogimedence.hu\/index.php\/2018\/06\/25\/iden-is-var-a-tokodi-borut\/","og_site_name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","article_publisher":"https:\/\/www.facebook.com\/dorogimedence\/","article_published_time":"2018-06-25T15:04:19+00:00","og_image":[{"width":670,"height":365,"url":"https:\/\/i0.wp.com\/dorogimedence.hu\/wp-content\/uploads\/2018\/06\/tokodi-borut-01.jpg?fit=670%2C365&ssl=1","type":"image\/jpeg"}],"author":"dorogimedence.hu","twitter_card":"summary_large_image","twitter_misc":{"Szerz\u0151:":"dorogimedence.hu"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/06\/25\/iden-is-var-a-tokodi-borut\/#article","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/06\/25\/iden-is-var-a-tokodi-borut\/"},"author":{"name":"dorogimedence.hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4"},"headline":"Id\u00e9n is v\u00e1r a Tokodi Bor\u00fat","datePublished":"2018-06-25T15:04:19+00:00","mainEntityOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/06\/25\/iden-is-var-a-tokodi-borut\/"},"wordCount":103,"publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/06\/25\/iden-is-var-a-tokodi-borut\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/06\/tokodi-borut-01.jpg","keywords":["borfesztiv\u00e1l","fesztiv\u00e1l","koncert","sz\u00f3rakoz\u00e1s","Tokod","Tokodi Bor\u00fat"],"articleSection":["H\u00edrek","Tokod"],"inLanguage":"hu"},{"@type":"WebPage","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/06\/25\/iden-is-var-a-tokodi-borut\/","url":"https:\/\/dorogimedence.hu\/index.php\/2018\/06\/25\/iden-is-var-a-tokodi-borut\/","name":"Id\u00e9n is v\u00e1r a Tokodi Bor\u00fat","isPartOf":{"@id":"https:\/\/dorogimedence.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/06\/25\/iden-is-var-a-tokodi-borut\/#primaryimage"},"image":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/06\/25\/iden-is-var-a-tokodi-borut\/#primaryimage"},"thumbnailUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/06\/tokodi-borut-01.jpg","datePublished":"2018-06-25T15:04:19+00:00","breadcrumb":{"@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/06\/25\/iden-is-var-a-tokodi-borut\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dorogimedence.hu\/index.php\/2018\/06\/25\/iden-is-var-a-tokodi-borut\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/06\/25\/iden-is-var-a-tokodi-borut\/#primaryimage","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/06\/tokodi-borut-01.jpg","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2018\/06\/tokodi-borut-01.jpg","width":670,"height":365},{"@type":"BreadcrumbList","@id":"https:\/\/dorogimedence.hu\/index.php\/2018\/06\/25\/iden-is-var-a-tokodi-borut\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/dorogimedence.hu\/"},{"@type":"ListItem","position":2,"name":"Id\u00e9n is v\u00e1r a Tokodi Bor\u00fat"}]},{"@type":"WebSite","@id":"https:\/\/dorogimedence.hu\/#website","url":"https:\/\/dorogimedence.hu\/","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","description":"Dorog, Keszt\u00f6lc, Le\u00e1nyv\u00e1r, Piliscs\u00e9v, Tokod, Tokodalt\u00e1r\u00f3, Csolnok, Esztergom-kertv\u00e1ros: h\u00edrek, programok","publisher":{"@id":"https:\/\/dorogimedence.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dorogimedence.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"},{"@type":"Organization","@id":"https:\/\/dorogimedence.hu\/#organization","name":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l","url":"https:\/\/dorogimedence.hu\/","logo":{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/","url":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","contentUrl":"https:\/\/dorogimedence.hu\/wp-content\/uploads\/2021\/04\/logo-feher-600.png","width":600,"height":100,"caption":"Dorogi-medence Region\u00e1lis H\u00edrport\u00e1l"},"image":{"@id":"https:\/\/dorogimedence.hu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dorogimedence\/"]},{"@type":"Person","@id":"https:\/\/dorogimedence.hu\/#\/schema\/person\/ce6091eeb7e95ecdc87890d6aa8e0fd4","name":"dorogimedence.hu","image":{"@type":"ImageObject","inLanguage":"hu","@id":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","url":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","contentUrl":"\/\/www.gravatar.com\/avatar\/d8d45f8901aadff40a4af72c0b826f1d?s=96&#038;r=g&#038;d=mm","caption":"dorogimedence.hu"}}]}},"_links":{"self":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/10863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/comments?post=10863"}],"version-history":[{"count":0,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/posts\/10863\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media\/10864"}],"wp:attachment":[{"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/media?parent=10863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/categories?post=10863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dorogimedence.hu\/index.php\/wp-json\/wp\/v2\/tags?post=10863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}